{"id":2888,"count":1,"description":"","link":"https:\/\/berliner-predigten.de\/blog\/tag\/gebrochen\/","name":"gebrochen","slug":"gebrochen","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/berliner-predigten.de\/blog\/wp-json\/wp\/v2\/tags\/2888","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/berliner-predigten.de\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/berliner-predigten.de\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/berliner-predigten.de\/blog\/wp-json\/wp\/v2\/posts?tags=2888"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}