{"id":2427,"count":1,"description":"","link":"https:\/\/berliner-predigten.de\/blog\/tag\/gottes-eigenschaften\/","name":"Gottes Eigenschaften","slug":"gottes-eigenschaften","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/berliner-predigten.de\/blog\/wp-json\/wp\/v2\/tags\/2427","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/berliner-predigten.de\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/berliner-predigten.de\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/berliner-predigten.de\/blog\/wp-json\/wp\/v2\/posts?tags=2427"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}