{"id":2229,"count":1,"description":"","link":"https:\/\/berliner-predigten.de\/blog\/tag\/ein-geistlicher\/","name":"ein Geistlicher","slug":"ein-geistlicher","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/berliner-predigten.de\/blog\/wp-json\/wp\/v2\/tags\/2229","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/berliner-predigten.de\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/berliner-predigten.de\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/berliner-predigten.de\/blog\/wp-json\/wp\/v2\/posts?tags=2229"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}