{"id":542,"date":"2019-09-22T12:05:42","date_gmt":"2019-09-22T10:05:42","guid":{"rendered":"https:\/\/berliner-predigten.de\/blog\/?p=542"},"modified":"2021-02-12T08:44:09","modified_gmt":"2021-02-12T07:44:09","slug":"bist-du-geistlich-reif","status":"publish","type":"post","link":"https:\/\/berliner-predigten.de\/blog\/2019\/09\/22\/bist-du-geistlich-reif\/","title":{"rendered":"Bist du geistlich reif?"},"content":{"rendered":"<p>Seid m\u00e4nnlich und stark, echte M\u00e4nnlichkeit ist Gott\u00e4hnlichkeit.<\/p>\n<audio class=\"wp-audio-shortcode\" id=\"audio-542-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/berliner-predigten.de\/dateien\/2019-09-22-Bist-du-geistlich-reif.mp3?_=1\" \/><a href=\"https:\/\/berliner-predigten.de\/dateien\/2019-09-22-Bist-du-geistlich-reif.mp3\">https:\/\/berliner-predigten.de\/dateien\/2019-09-22-Bist-du-geistlich-reif.mp3<\/a><\/audio>\n<p><!--more--><\/p>\n<p><strong>Stichworte:<\/strong> faule Fr\u00fcchte &#8211; Unkraut &#8211; Runterkommen &#8211; Konflikte &#8211; Demut &#8211; Stille &#8211; Standfestigkeit &#8211; Genie\u00dfbarkeit &#8211; M\u00e4nnlichkeit<\/p>\n<p>Wer uns unterst\u00fctzen m\u00f6chte, kann dies hier tun: <a href=\"https:\/\/berliner-predigten.de\/blog\/spenden\/\" target=\"_blank\" rel=\"noopener noreferrer\">\u2665 Spenden \u2665<\/a><\/p>\n<p><em>Predigt herunterladen: <a href=\"https:\/\/berliner-predigten.de\/dateien\/2019-09-22-Bist-du-geistlich-reif.mp3\" target=\"_blank\" rel=\"noopener noreferrer\">2019-09-22 Bist du geistlich reif?<\/a><\/em><\/p>\n<p><em> Original der Mitschrift: <a href=\"https:\/\/www.gemeindezentrum.berlin\/predigtmitschriften\/241-bist-du-geistlich-reif\" target=\"_blank\" rel=\"noopener noreferrer\">Bist du geistlich reif?<\/a><\/em><\/p>\n<p><a href=\"https:\/\/berliner-predigten.de\/blog\/wp-content\/uploads\/2019\/09\/190922-seid-maennlich-und-stark-1.jpg\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-9443\" src=\"https:\/\/berliner-predigten.de\/blog\/wp-content\/uploads\/2019\/09\/190922-seid-maennlich-und-stark-1.jpg\" alt=\"\" width=\"90\" height=\"90\" srcset=\"https:\/\/berliner-predigten.de\/blog\/wp-content\/uploads\/2019\/09\/190922-seid-maennlich-und-stark-1.jpg 949w, https:\/\/berliner-predigten.de\/blog\/wp-content\/uploads\/2019\/09\/190922-seid-maennlich-und-stark-1-300x300.jpg 300w, https:\/\/berliner-predigten.de\/blog\/wp-content\/uploads\/2019\/09\/190922-seid-maennlich-und-stark-1-150x150.jpg 150w, https:\/\/berliner-predigten.de\/blog\/wp-content\/uploads\/2019\/09\/190922-seid-maennlich-und-stark-1-768x768.jpg 768w\" sizes=\"auto, (max-width: 90px) 100vw, 90px\" \/><\/a><\/p>\n<hr \/>\n<p><em>(Es gilt das gesprochene Wort.)<\/em><\/p>\n<p>Preis dem Herrn! Dies ist der Tag, den der Herr gemacht hat! Lasset uns freuen und fr\u00f6hlich sein! Ein wundervoller Gnadentag! Die Sonne scheint! Gott hat uns lieb, jeden Einzelnen von uns, und ich preise den Herrn! Halleluja! Ich freue mich, dass ich hier sein darf dank der Gnade Gottes! Ich w\u00e4re vielleicht nicht hier, sondern irgendwo, aber ich bin im Hause des Herrn! Und ein Tag im Hause des Herrn ist besser als tausend Tage irgendwo anders! David sprach folgende Worte aus: Es steht geschrieben: <em><strong><u>Ein Tag in deinen Vorh\u00f6fen ist besser als sonst tausend; ich will lieber an der Schwelle im Haus meines Gottes stehen als wohnen in den Zelten der Gottlosen! <\/u><\/strong><\/em><strong><u>(Ps 84,11)<\/u><\/strong>\u00a0Lieber m\u00f6chte er Pf\u00f6rtner im Hause Gottes sein, als in den Pal\u00e4sten der Menschen zu wohnen! Verstehst du? Das hei\u00dft, er zog es vor, drau\u00dfen zu verweilen. Mein heutiges Thema lautet wie folgt: Bist du geistlich reif? Wie weit bist du? Bist du geistlich erwachsen und m\u00fcndig? Ist es m\u00f6glich, dich &#8218;auf die Menschheit loszulassen?&#8216; Das ist die Frage, welche mich heute bewegt. Der Herr will die Christen zur geistlichen Reife bringen! Es gibt zahlreiche Mitl\u00e4ufer, die nur \u201eHalleluja!\u201c schreien, obwohl nichts dahinter ist: weder Korn noch irgendetwas Bleibendes. Bist du wirklich reif? Bist du wiedergeboren? Bist du schon eine neue Sch\u00f6pfung geworden? Das sind die Fragen, welche ich heute bewegen m\u00f6chte. Bist du schon ein Kind des himmlischen Vaters und wei\u00dft du das hundertprozentig oder glaubst du es zumindest? Wir sollten fest davon \u00fcberzeugt sein und wissen, dass es sich so verh\u00e4lt! Bist du schon m\u00fcndig und erwachsen? Kann der Herr schon etwas mit dir beginnen? Kann Er dich irgendwo einsetzen und ben\u00fctzen, z.B. zum Geschirrsp\u00fclen, Toilettenreinigen, zur Stra\u00dfen-Evangelisation o.\u00c4.?<\/p>\n<p>Hast du schon den Heiligen Geist empfangen? Diese Frage richtete Apostel Paulus an einige J\u00fcnger, wie nachfolgend geschrieben steht: <strong><u>Zu denen sprach er: Habt ihr den Heiligen Geist empfangen, als ihr gl\u00e4ubig wurdet? Sie sprachen zu ihm: Wir haben noch nie geh\u00f6rt, dass es einen Heiligen Geist gibt (Apg 19,2).<\/u><\/strong> Sie wurden schl\u00e4frig im Gottesdienst! Er \u00e4u\u00dferte soviel wie: \u201eDa stimmt etwas nicht mit euch! Ihr seid Christen und sogar getauft, doch bei euch passiert nichts! Warum verh\u00e4lt sich das so?\u201c Seine gro\u00dfe Frage lautete: \u201eHabt ihr den Heiligen Geist empfangen?\u201c Heute werde ich ein paar Kriterien ansprechen, die aufdecken, was der Pr\u00fcfstein f\u00fcr geistliche Reife ist. Der Herr sucht reife und vollkommene Frucht! Mit unausgereifter Frucht kann Er nichts beginnen! Versuche nicht, dem Herrn eine faule Frucht zu servieren, denn Er will etwas Gutes, Perfektes und Vollkommenes! Guten Weizen bzw. gute und reife Fr\u00fcchte begehrt Er! Wir sollen damit beginnen, in unserem Leben das Unkraut zu erkennen! Das war das Erste, was bei meiner Bekehrung stattfand!<\/p>\n<p>Ich m\u00f6chte stets von dem ausgehen, was ich selbst in den letzten f\u00fcnfzig Jahren erlebte und erfuhr. Damals stellte ich fest, &#8218;wie viel Unkraut in meinem G\u00e4rtchen ist&#8216;. Ich dachte, ich w\u00e4re schon perfekt und edel gleichwie eine wunderbare Person, die noch niemals ges\u00fcndigt hat. Als der Evangelist Werner Heukelbach schrieb: \u201eHerr Matutis, bekennen Sie dem Herrn Jesus Christus Ihre S\u00fcnden und Er wird Sie von aller Schuld freisprechen!\u201c, erwiderte ich, dass ich keine S\u00fcnden h\u00e4tte und fehlerfrei sei. Er sprach Folgendes: \u201eDenken Sie \u00fcber Ihr Leben nach! Haben Sie noch nie etwas Schlechtes getan? Hatten Sie niemals schlechte Absichten? Haben Sie noch nie gestohlen, gelogen oder jemanden betrogen?\u201c Daraufhin legte ich ein Heft an und begann damit, alle Fehler zu notieren, die ich in meinem Leben getan hatte, denn diese Empfehlung gab er mir. Ein Heft reichte nicht aus; es wurden zwei! Ich stellte fest, dass ich ein S\u00fcnder war und sprach: \u201eGott, sei mir S\u00fcnder gn\u00e4dig!\u201c Auf diesem Weg fand ich zum Heiland. Wir glauben, dass wir perfekt seien. Unkraut sind auch Blumen! Das ist auch ein Gew\u00e4chs, welches sch\u00f6n gereift, frisch, gr\u00fcn und saftig aussieht! Aber das gen\u00fcgt nicht!<\/p>\n<p>Der Herr will uns mobilisieren. Er will uns zeigen, wie es sich mit uns verh\u00e4lt. Eines der besten Beispiele f\u00fcr guten Weizen ist das Leben des Apostel Paulus. Der perfekte Pharis\u00e4er von Pharis\u00e4ern tat von sich selbst Folgendes kund: \u201eEs ist keine S\u00fcnde in meinem Leben! Ich habe noch nie etwas verkehrt gemacht!\u201c Als der Herr Jesus ihm auf der Stra\u00dfe nach Damaskus begegnete, wurde ersichtlich, was f\u00fcr ein Verbrecher er war, wie viele Leute er hinter Gitter gebracht hatte und was er alles Verwerfliches tat. Er hatte eine ganze Gemeinde in Jerusalem zerst\u00f6rt. So wie ich die Entwicklung von Apostel Paulus betrachte, sehe ich die meine, betrachte mein Leben geistlich, beurteile mich selbstkritisch und ziehe mich selbst zur Rechenschaft.<\/p>\n<p>Ich gehe auf seine ersten, \u00e4ltesten Briefe ein. Darin erkl\u00e4rt der Apostel, dass er einer der bedeutendsten, besten und sch\u00e4rfsten Evangelisten w\u00e4re! Er beschreibt darin, wie gut und stark er ist und wie er f\u00fcr den Herrn eifert. (Siehe 2 Kor 11) F\u00fcnf Jahre darauf beurteilt er sich anders, wie nachfolgend geschrieben steht: <strong><u>Denn ich bin der geringste unter den Aposteln, der ich nicht wert bin, dass ich ein Apostel hei\u00dfe, weil ich die Gemeinde Gottes verfolgt habe (1 Kor 15,9).<\/u><\/strong> Paulus \u00e4u\u00dfert hier, dass er einer der geringsten Apostel sei. Du siehst: er kommt auf den Boden der Tatsachen zur\u00fcck. Viele Christen halten sich im Himmel, Wolke Nummer neun, acht oder sieben, auf. Wiederum f\u00fcnf Jahre sp\u00e4ter, nachdem er den n\u00e4chsten Brief an die Epheser verfasste, macht er Folgendes verlautbar. Es steht geschrieben: <strong><u>Mir, dem allergeringsten unter allen Heiligen, ist die Gnade gegeben worden, den Heiden zu verk\u00fcndigen den unausforschlichen Reichtum Christi (Eph 3,8).<\/u><\/strong> Paulus gibt preis, dass er der Kleinste unter den Heiligen sei! Zuerst \u00e4u\u00dfert er Folgendes: \u201eIch bin ein Studierter! Ich war bei Professor Gamaliel! Ich habe Theologie studiert!\u201c Er z\u00e4hlt auf, was er alles w\u00e4re: ein Pharis\u00e4er von Pharis\u00e4ern, ein Israelit, dem Stamm Benjamin zugeh\u00f6rig u.a. Doch dann findet er zur\u00fcck zur Realit\u00e4t. In einem seiner letzten Briefe macht der Apostel Paulus Folgendes verlautbar: Es steht geschrieben: <strong><u>Das ist gewisslich wahr und ein teuer wertes Wort: Christus Jesus ist in die Welt gekommen, die S\u00fcnder selig zu machen, unter denen ich der erste bin (1 Tim 1,15).<\/u><\/strong> \u201eIch bin der gr\u00f6\u00dfte S\u00fcnder!\u201c, tut er \u00f6ffentlich kund!<\/p>\n<p>Nacheinander l\u00e4uft folgende Entwicklung ab: \u201eIch bin der geringste Apostel!\u201c, \u201eIch bin der kleinste der Heiligen!\u201c, und am Schluss: \u201eIch bin der gr\u00f6\u00dfte S\u00fcnder!\u201c <em>Das<\/em> ist geistliche Reife! Die meisten Christen denken, dass sie perfekt w\u00e4ren, aber es verh\u00e4lt sich gerade umgekehrt! Paulus sprach: \u201eIch bin der gr\u00f6\u00dfte S\u00fcnder!\u201c Er erachtete sich selbst f\u00fcr gering, obgleich er im ersten Jahrhundert einer der gr\u00f6\u00dften Apostel war! Das fand statt, weil er sich nicht mehr wichtig nahm! Geistliche Reife hei\u00dft, sich nicht mehr wichtig zu nehmen und zu sagen: \u201eAuf mich kommt es nicht an! Das Leben geht weiter, mit mir oder ohne mich! Die Erde dreht sich weiter!\u201c Wir m\u00fcssen Folgendes bedenken: Paulus, der als ein junger Mann zu Jesus fand und zum Glauben kam, war sehr arrogant und eingebildet. Uns ergeht es gleicherma\u00dfen. Wir \u00e4u\u00dfern Worte wie die folgenden: \u201eIch bin ein Deutscher!\u201c, \u201eIch bin ein Katholik!\u201c, \u201eIch bin ein Protestant!\u201c, \u201eIch bin evangelisch bzw. pfingstlerisch!\u201c Wei\u00df der Kuckuck, was du bist! Das ist \u00fcberhaupt nicht wichtig! Komm runter! Paulus lobte die Galater daf\u00fcr, dass sie ihn wie einen Engel aufnahmen. Als etwas Besonderes wurde er von den Galatern eingesch\u00e4tzt. Folgendes wurde \u00fcber den Apostel preisgegeben: \u201eJetzt kommt ein studierter Theologe!, Saul von Tarsus ist ein Adliger, ein R\u00f6mer!\u201c Sie nahmen ihn wie einen Engel auf, obwohl sein Fleisch bzw. \u00e4u\u00dferes Erscheinungsbild f\u00fcr sie hernach zum Pr\u00fcfstein gereicht war. Dadurch wurden sie von sich eingenommen und lie\u00dfen verlauten, dass sie prima und perfekt seien.<\/p>\n<p>Wie reif bist du geistlich?, ist die Frage, die ich dir stellen m\u00f6chte. Bildest du dir auch etwas ein auf deine Abstammung und sagst: \u201eIn meinen Adern flie\u00dft blaues Blut! Ich stamme von den Juden ab! Ich bin aus dem Stamm Benjamin! Ich bin dieses oder jenes!\u201c Wir sehen, was Paulus in seinem Leben alles feststellte! Sinne dar\u00fcber nach, was geschrieben steht! Das Wort des Herrn, welches gem\u00e4\u00df der \u00dcberlieferung aus der Heiligen Schrift offenbar wurde und nachfolgend niedergeschrieben steht, lautet wie folgt: <strong><u>Seht doch, Br\u00fcder und Schwestern, auf eure Berufung. Nicht viele Weise nach dem Fleisch, nicht viele M\u00e4chtige, nicht viele Vornehme sind berufen.\u00a0Sondern was t\u00f6richt ist vor der Welt, das hat Gott erw\u00e4hlt, damit er die Weisen zuschanden mache (1 Kor 1,26-27a).<\/u><\/strong> Das Reich Gottes besteht aus Dummk\u00f6pfen! Bitte, h\u00f6rt mir gut zu und erschreckt nicht! Es setzt sich aus Ungebildeten, Sklaven, einfachen Leuten, Arbeitern und ganz wenig anderen zusammen. Jene sind darinnen vereint! Aus einer Textpassage tritt Folgendes zutage: \u201eUnd gr\u00fc\u00dfe mir aus dem K\u00f6nigshaus diese und jene.\u201c Es waren schon ein paar Edle vorhanden, aber das betraf eine Minderheit.<\/p>\n<p>Ein echter Christ, der zum Glauben fand, der tats\u00e4chlich gereift und erfahren ist, wird klein und bildet sich nichts mehr auf seinen Reichtum ein! Ich betete einstmals daf\u00fcr, dass der Herr mir in meine Heilbronner Gemeinde Million\u00e4re schicken m\u00f6ge und Er f\u00fcgte einige davon hinzu. Doch Folgendes viel mir auf: diese waren einfache Leute, welche in Jeanshosen zum Gottesdienst kamen, im Gegensatz zu jenen, welche mit Frack, Zylinder und Fliege gekleidet den Weg zur Versammlung fanden. Die Million\u00e4re waren schlicht, einfach und simpel. Sie hielten nicht viel von sich selbst, denn sie wussten, dass Geld, gleichfalls Wissen, K\u00f6nnen und Perfektionismus, nicht alles ist! \u201eNicht viele Weise!\u201c, spricht der Herr! Gott erw\u00e4hlt das Schwache steht in der Heiligen Schrift! Das schwache Geschlecht sind die Frauen! Es ist erstaunlich! Im Reich Gottes gibt es mehr Frauen als M\u00e4nner! Vermutlich haben sie eine andere Pr\u00e4gung erhalten. Der Mann will alles verstehen und begreifen. In Bayern stellte ich fest, dass sich neben der Katholischen Kirche jeweils ein Wirtshaus befand. Die Frauen gingen in die Kirche zum Beten und die M\u00e4nner gingen ins Wirtshaus. Nachdem der Pfarrer das \u201eAmen\u201c aussprach, fanden sie auf dem Nachhauseweg wieder zusammen und hegten Gemeinschaft! Vielleicht fand diese Pr\u00e4gung bereits im Mittelalter statt. Eigentlich sollten glaubensstarke M\u00e4nner in der Kirche sein, denn der Glaube ist vorrangig M\u00e4nnersache. Darauf gehe ich sp\u00e4ter ein. \u201eSeid m\u00e4nnlich und stark!\u201c, hei\u00dft es einmal in der Heiligen Schrift. Das gilt auch f\u00fcr das weibliche Geschlecht, nicht nur f\u00fcr die M\u00e4nner. Unsere Gesellschaft ist verweiblicht und verweichlicht! Es gibt fast nur noch Feiglinge unter den Menschen! Im Islam wiederum gibt es beinahe ausschlie\u00dflich M\u00e4nner, und in der Synagoge der Juden gleichfalls. Ich frage mich, wo in der Christenheit die M\u00e4nner geblieben sind? Der Herr erw\u00e4hlte das Schw\u00e4chliche und das Niedrige, das Kleine und das Nichtige, um zu besch\u00e4men die M\u00e4chtigen, welche \u00e4u\u00dfern: \u201eWir Juden!\u201c, \u201eWir M\u00e4nner!\u201c, \u201eWir Moslems!\u201c oder \u201eWir Christen!\u201c Paulus holte sie zur\u00fcck auf den Boden der Tatsachen. Der Herr erw\u00e4hlt das, was nichts ist!<\/p>\n<p>David erblickte als das achte Kind das Licht der Welt. Samuel kam, um f\u00fcr Israel einen K\u00f6nig zu salben. Der Vater namens Isai brachte zuerst den gro\u00dfen, stattlichen, erstgeborenen Sohn, worauf der Prophet \u00e4u\u00dferte, dass jener es nicht sei. Der Reihe nach traten alle sieben S\u00f6hne vor Samuel. Keiner von ihnen wurde f\u00fcr gut befunden. Daraufhin fragte der Prophet Isai: \u201eSag mal, hast du nicht noch einen Sohn?\u201c Vielleicht dachte er Folgendes: \u201eDann nehmen wir ein M\u00e4dchen, wenn es keinen weiteren Sohn mehr gibt.\u201c Doch Isai sprach: \u201eDrau\u00dfen auf der Weide ist mein j\u00fcngster Sohn David. Er ist ein Hirtenjunge, der die L\u00e4mmer weidet!\u201c Er rief nach ihm, und als er das Haus seines Vaters betrat, fand die Best\u00e4tigung durch den Heiligen Geist statt. Der Prophet sch\u00fcttete das Horn mit Salb\u00f6l \u00fcber ihn aus und eilte von dannen, da diese Handlung aus folgendem Grund gef\u00e4hrlich war: die Regierungszeit des K\u00f6nigs war noch nicht vollendet. Der Herr erw\u00e4hlt die Kleinsten, Bescheidensten, Unsichtbarsten und Unbequemsten, sprich, das was Nichts ist in der Welt!<\/p>\n<p>Menschen wie David sind gelehrig! Der Herr kann sie noch formen und pr\u00e4gen! David musste noch viele Konflikte in seinem Leben l\u00f6sen! Gott lie\u00df ihn zur Reife und Vollendung gelangen! Mein Thema ist Reife! Durch Konflikte wirst du reif! Laufe den Konflikten und Spannungen, welcher Art auch immer, nicht weg, sondern l\u00f6se sie! Dadurch gelangst du zur Reife! Ein Mensch, der Konflikte hat, bildet sich nichts ein! Eine solche Person wei\u00df, dass jeder Mensch zu k\u00e4mpfen hat. &#8218;Wir kochen alle mit Wasser.&#8216; Christen wie Nichtchristen haben Schwierigkeiten! Es gibt viele Personen, die Folgendes \u00e4u\u00dfern: \u201eIch bin Christ. Deshalb habe ich keine Probleme! Lob und Dank!\u201c Nein! Das Gegenteil ist der Fall! Wir haben mehr Probleme und Schwierigkeiten als Nichtchristen! Am eigenen Leibe musste ich erfahren, wie mich die Gemeindemitglieder betrogen. Sie sprachen zu mir Folgendes: \u201eBruder Matutis! Wenn Sie zum Heiland kommen, haben Sie keine Probleme mehr!\u201c Doch ich hatte sogar sehr viele davon! Ich fragte mich, woher diese Probleme auf einmal alle kommen w\u00fcrden. Doch gerade dadurch entwickelte ich mich, wurde reif und wuchs im Glauben an den Herrn. Ich wurde dem\u00fctig und still und h\u00f6rte auf, andere Personen zu richten. Ich stellte fest, dass ich die gleichen Probleme hatte wie die anderen. Gott schenkt den Dem\u00fctigen Gnade! Wenn man Probleme hat, \u00fcbt man Stillschweigen, echauffiert sich nicht mehr \u00fcber die anderen und h\u00f6rt auf damit, sie zu kritisieren.<\/p>\n<p>Unser Stolz behindert die geistliche Reife! Von wegen: \u201eIch habe den Heiligen Geist!\u201c Das ist mir v\u00f6llig egal! Daf\u00fcr kannst du dir nichts kaufen! Lebe zuerst einmal den Heiligen Geist aus in deinem Dasein! Sage nicht nur: \u201eIch habe den Geist des Herrn!\u201c oder \u201eMein Vater ist ein gro\u00dfer Mann!\u201c Es geht darum, das zu werden, was der Herr aus dir machen wollte!\u201c Stolz war die Urs\u00fcnde des Teufels! Dadurch kam er zu Fall. Stolz, Einbildung und Arroganz ist das, was vielen Christen noch vom Teufel anhaftet. Das ist in ihnen verblieben. Sie bringen es mit in die Gemeinde und bilden sich etwas ein. Sie sagen: \u201eIch bin perfekt, aber diese oder jener noch nicht!\u201c Wir kritisieren viele Personen. Jesus lebte Demut aus! Er demonstrierte den Menschen, was Abh\u00e4ngigkeit vom Herrn ist! Er lehrte Ehrfurcht vor dem Herrn! So spricht der Herr: <strong><u>Die Furcht des Herrn ist der Weisheit Anfang (Ps 111,10a).<\/u><\/strong> D.h. Folgendes: \u201eIch muss aufpassen auf mein christliches Leben, darauf, dass ich keine Fehler begehe, meinen Respekt vor dem Herrn nicht verliere und dass ich immer allein auf Ihn schaue!\u201c \u201eSchau&#8216; auf Jesus!\u201c, dieses Lied sangen wir heute.<\/p>\n<p>Durch Klatsch und Tratsch werden wir abgelenkt von der wichtigsten Sache des Lebens! Je mehr wir uns dem Herrn anvertrauen, desto gef\u00e4hrlicher leben wir, desto stolzer und eingebildeter werden wir! Wir denken dann, dass wir bereits Heilige w\u00e4ren! Viele meinen, sie seien bereits Heilige nach drei bis vier Jahren Gemeindezugeh\u00f6rigkeit. Wir reifen und m\u00fcssen dem\u00fctig werden! \u201eIch wei\u00df, dass ich nichts wei\u00df!\u201c, \u00e4u\u00dferte einmal eine weise Person. Selbst dann, wenn du die Bibel einmal, zweimal oder bereits zehn Mal durchgelesen hast, wei\u00dft du noch nicht alles! Ich wei\u00df auch nicht alles! Ich bin noch nicht so weit! Das muss ich immer wieder in meinem pers\u00f6nlichen Leben feststellen. Ich liebe den Heiland, schon viele Jahrzehnte sogar, aber ich bin noch nicht so weit. \u201eWo bin ich \u00fcberhaupt?\u201c, frage ich mich selbst. Die Richtung stimmt bei mir, aber alles andere ist noch nicht vollkommen. Ich muss mich noch entwickeln.<\/p>\n<p>Ein Zeichen daf\u00fcr, dass man in der Demut gereift ist, ist dieses, dass sich eine Person belehren l\u00e4sst. Au\u00dferdem gibt man zu, dass man noch lernt und noch nicht alles wei\u00df. Man gibt Folgendes preis: \u201eIch wei\u00df nicht alles! Ich muss mal \u00fcberlegen, mal nachschlagen, mal Gott fragen!\u201c Manche Christen sind wie Jehovas Zeugen. Sie behaupten, dass sie alles wissen. Jemand schrieb in seiner Brosch\u00fcre &#8218;Der Wachturm&#8216; das Folgende: \u201eEs gibt nichts, was ich nicht zu erkl\u00e4ren vermag!\u201c Das ist Unfug! Es gibt bis zum heutigen Tage viel Unerkl\u00e4rbares, trotz des technischen Fortschritts, der Computer usw. Der dem\u00fctige Mensch sagt: \u201eIch muss lernen! Ich ben\u00f6tige Weisheit! Ich brauche Salbung!\u201c Sogar von Jesus hei\u00dft es, als Er als Zw\u00f6lfj\u00e4hriger im Tempel weilte und dessen Eltern Richtung Heimst\u00e4tte zogen, wie nachfolgend geschrieben steht: <strong><u>Und Jesus nahm zu an Weisheit, Alter und Gnade bei Gott und den Menschen (Lk 2,52).<\/u><\/strong> Und das, obwohl Er alles wusste und Ihm alles zugetan war! <em>Das<\/em> ist Reife! Jesus reifte in den achtzehn Jahren in Nazareth. Er war gelehrig! Er lernte sowohl von Seinem Vater Josef als auch von Seinen Geschwistern! Er hatte vier Br\u00fcder. W\u00e4hrend sie miteinander umgingen, spielten oder arbeiteten, lernte Er von ihnen durch Konflikte und Auseinandersetzungen.<\/p>\n<p>H\u00f6re gut zu! Willst du erfolgreich werden? Erfolgreiche Menschen in fast allen Bereichen, vor allem Manager in hohen Positionen, lernen st\u00e4ndig dazu! Sobald sie etwas h\u00f6ren, forschen sie nach und fragen: \u201eWer behauptet das? Aus welchem Zusammenhang heraus wurde das gesagt?\u201c Sie h\u00f6ren anderen zu, ohne selbst viel zu sprechen. Sie h\u00f6ren zu, schweigen und &#8217;suchen \u00fcberall Gold, Edelsteine, Diamanten oder Perlen&#8216;. Erfolgreiche Menschen lernen aus den Fehlern der anderen, nicht nur aus ihren eigenen. Sie wollen Wissen anh\u00e4ufen und es darreichen und weitergeben. Erfolgreiche Menschen wollen ergr\u00fcnden, welcher Lehrer der Beste f\u00fcr sie ist. Wenn Gl\u00e4ubige beginnen w\u00fcrden gleichfalls so zu denken, w\u00fcrde ihr christliches Leben anders aussehen.<\/p>\n<p>Menschen, die Erfahrungen haben, die durch Tiefen gingen, die den Teufel kennenlernten, die durch Leiden, sowohl durch H\u00f6hen als auch durch dunkle T\u00e4ler gef\u00fchrt wurden, sind gelehrig! Die erfolgreichsten Menschen haben Lehrer aufgesucht. Es ist Gnade, wenn du einen solchen Lehrer findest! Du begegnest heute keinen erfolgreichen Menschen mehr, die dich weiterf\u00fchren; die <em>mehr<\/em> sind, die <em>mehr<\/em> k\u00f6nnen, die <em>mehr<\/em> erlebt haben. Paulus sprach: \u201eIch sa\u00df zu den F\u00fc\u00dfen des Professor Gamaliel!\u201c Der gro\u00dfe Rabbiner Hillel aus Jerusalem war dessen Gro\u00dfvater. Er war ein weiser Israelit und Patriarch. Gamaliel sprach einmal die folgenden Worte aus: \u201eSuche dir einen Lehrer! Halte dich nicht bei zwiesp\u00e4ltigen Leuten auf! Gew\u00f6hne dich daran, den Zehnten zu verzehnten!\u201c Es ging ums Geld! Sei nicht gleichg\u00fcltig und oberfl\u00e4chlich und sage: \u201eDer Herr kriegt was \u00fcbrig bleibt!\u201c W\u00e4ge den Zehnten nicht ab! Bringe Gott nicht um Seinen Anteil! Das ist Wissen! Spiele dem Herrn kein Theater vor! Ein weiterer Satz von Gamaliel war Folgender: \u201eIch bin unter Weisen aufgewachsen und habe nichts besseres f\u00fcr den K\u00f6rper gefunden als das Schweigen.\u201c Sein Gro\u00dfvater kam, sa\u00df und h\u00f6rte zu, was er sprach; das ist reifen! Reife Menschen verhalten sich still. Sie lassen den Mund zu. Viele Menschen reden, aber sagen nichts. Nicht das Forschen ist die Hauptsache, sondern das Tun! Wer viel redet, bringt S\u00fcnde hervor! Das ist uns nicht neu. Es steht im Alten Testament der Bibel.<\/p>\n<p>Was ist geistliche Reife? Es steht geschrieben:<strong><u> Aber was Gott uns schenken will, ist noch viel mehr. Darum hei\u00dft es auch: \u201eDie Hochm\u00fctigen weist Gott von sich; aber er wendet denen seine Liebe zu, die wissen, dass sie ihn brauchen.\u201c (Jak 4,6)<\/u><\/strong> Unterordne dich dem Herrn! Wer sich vor Gott dem\u00fctigt wird von Gott erh\u00f6ht zur richtigen Zeit; im richtigen Augenblick! Dem\u00fctige dich vor dem Herrn! Bleibe klein, bleibe unten, reg&#8216; dich nicht auf! Reife ist N\u00fcchternheit und Wachsamkeit! So spricht der Herr:<strong> <u>Seid n\u00fcchtern und wacht; denn euer Widersacher, der Teufel, geht umher wie ein br\u00fcllender L\u00f6we und sucht, wen er verschlinge (1 Petr 5,8).<\/u><\/strong>\u00a0Der Teufel, unser Gegner, geht umher wie ein br\u00fcllender L\u00f6we und versucht uns zu verschlingen! H\u00f6rst du! Der L\u00f6we ist nicht gef\u00e4hrlich! Habe nicht vor dem br\u00fcllenden L\u00f6wen Angst, sondern vor den L\u00f6winnen! Die L\u00f6winnen sind gef\u00e4hrlich! Vater L\u00f6we br\u00fcllt zwar, sodass alle vor ihm fliehen, doch an den Platz, wohin sie fliehen, halten sich die L\u00f6winnen auf, welche schon auf dich warten, um dich zu verzehren! Habe mehr Angst vor den L\u00f6winnen, die stillschweigend auf der Pirsch sind und dir auflauern! Der Teufel br\u00fcllt wie ein L\u00f6we! Er will dich in die andere Richtung scheuchen! Begreifst du dieses Schauspiel, das sich in der Natur abspielt?<\/p>\n<p>Bist du schon geistlich reif? Hast du den B\u00f6sen bereits erkannt? Konnte der Herr dir eine Antwort geben? Hast du Ihn befragt?, und hat Er dir eine Antwort dargereicht auf nachfolgende Fragen: \u201eWoher, von wem, warum und wie kommen die Probleme auf mich zu? Was ist da los? Wie will der Teufel meinen Glauben zerst\u00f6ren?\u201c Widersteht fest im Glauben, steht in der Bibel, dem Wort des Herrn! (Siehe 1 Petr 5,9a) Betrachte diese Frage kritisch: \u201eWie widerstehe ich dem Feind?\u201c Folgende Erkenntnis f\u00fchrt zu geistlicher Reife: \u201eIch widerstehe dem Teufel im Leiden!\u201c Du tust etwas, was dir <em>nicht<\/em> liegt! Wenn du mit Ausdauer gelitten hast, wird der Herr dir Seine Gnade verleihen und dich zu Seiner Herrlichkeit f\u00fchren. Es steht geschrieben: <strong><u>So dem\u00fctigt euch nun unter die gewaltige Hand Gottes, damit er euch erh\u00f6he zu seiner Zeit (1 Petr 5,6).<\/u><\/strong> Er wird dich vervollst\u00e4ndigen, vollkommen machen, best\u00e4tigen, st\u00e4rken und etablieren! Alles wird offenbar werden! Das Nichtige vergeht! Viele Leute f\u00fcrchten sich vor Leiden und sprechen das folgende Gebet: \u201eHerr, lass die Schwierigkeiten nicht in mein Leben gelangen!\u201c Danke dem Herrn f\u00fcr deine Schwierigkeiten! Ich ermutige dich! Du wirst erstaunt sein, wie der himmlische Vater dich reifen l\u00e4sst, du pl\u00f6tzlich \u00fcber allem zu stehen und souver\u00e4n zu sein vermagst! Auf einmal bist du zu einem m\u00fcndigen Christen herangereift. Wenn du gereift bist, werden die Segnungen \u00fcber dein Leben kommen, wie hernach geschrieben steht: <strong><u>Der Gott aller Gnade aber, der euch berufen hat zu seiner ewigen Herrlichkeit in Christus, der wird euch, die ihr eine kleine Zeit leidet, aufrichten, st\u00e4rken, kr\u00e4ftigen, gr\u00fcnden.\u00a0Ihm sei die Macht in alle Ewigkeit! Amen (1 Petr 5,10f.).<\/u><\/strong> Du fragst: \u201eWarum werde ich nicht gesegnet? Warum passiert so wenig bei mir? Ich bete schon ein halbes Jahr und es geschieht nichts!\u201c Ja, du reifst!<\/p>\n<p>Wann reifst du au\u00dferdem? Wenn du in die Ruhe Gottes einkehrst und stille wirst vor dem Herrn! <strong><u>\u201eDer Herr wird f\u00fcr euch streiten, und ihr sollt stille sein!\u201c, tat der himmlische Vater den Israeliten kund. (Vgl. 2 Mose 14,14)<\/u><\/strong> Du reifst, wenn man dich in Frieden l\u00e4sst und du dir die Ruhe nimmst! Gehe durch die G\u00e4rten und betrachte die Obstb\u00e4ume! Ein Apfel h\u00e4ngt am Baum und genie\u00dft die Sonne sowie Stille und Ruhe. Eine Frucht reift in der Ruhe, in der Stille und im Frieden! Sie ist geborgen! Das haben die meisten Menschen nicht! Sie meinen, dass sie etwas f\u00fcr den Herrn tun m\u00fcssen und veranstalten eine Aktion nach der anderen! Der Herr ben\u00f6tigt keine Macher! Er will, dass du in die Ruhe Gottes einkehrst! Wer voller Stress ist, reift nicht! Das ist vielleicht ein Teil des Wachstums, aber nicht das, was der Herr will! Die Seele reift nur, indem du die Aufgaben des Lebens bew\u00e4ltigst, welche der Herr dir in den Weg stellt! Du willst zwar etwas anderes, aber tust das Folgende kund: \u201eHier muss ich durch!\u201c Du m\u00f6chtest einen Ausflug machen, durch die Welt reisen, etwas erleben, doch stattdessen wirst du &#8218;am Baum belassen, um zu reifen&#8216;. K\u00e4mpfe an der Reife! Wir m\u00fcssen m\u00fcndige Christen werden, anstatt christliche Experten! H\u00f6re, was Professor Gamaliel sprach! Er riet das Folgende: Es geht nicht um das Forschen, sondern um das Zuh\u00f6ren und Schweigen! Geistliche Reife tut hierzulande und allerorts Not! Es ist eine Seltenheit und Mangelware in der Christenheit! Wo findest du heutzutage noch eine geistliche Person? Da musst du weit fahren! Es steht geschrieben: <strong><u>So spricht der HERR Zebaoth: Zu jener Zeit werden zehn M\u00e4nner aus allen Sprachen der V\u00f6lker einen j\u00fcdischen Mann beim Zipfel seines Gewandes ergreifen und sagen: Wir wollen mit euch gehen, denn wir haben geh\u00f6rt, dass Gott mit euch ist (Sach 8,23).<\/u><\/strong> In der Endzeit wird es soweit kommen, dass die Menschen am Rockzipfel eines Juden h\u00e4ngen werden, von einem zum anderen Ende der Welt fahren und Lehre sowie Bildung suchen! Das ist ein prophetisches Sprachbild.<\/p>\n<p>Bevor ich Pastor wurde, musste ich vieles aufgeben und Verzicht \u00fcben. Ich konsumierte und lernte aus dem Wort meines himmlischen Vaters. Manchmal besuchte ich drei Gottesdienste an einem Tag! In M\u00fcnchen gab es verschiedene Gemeinden, und im Deutschen Museum &#8211; das fand ich wunderbar &#8211; waren mehrere Gemeinden gleichzeitig versammelt, sodass ich einfach nur hindurchtreten brauchte, um zu schauen, wo es etwas zu Lernen gab. Wem etwas gegeben ist, der wird gebraucht! So jemand erh\u00e4lt zus\u00e4tzlich zu den Gaben noch Aufgaben! Als Pastor bin ich gleich einem H\u00f6hlenforscher! Ich muss dazu bereit sein, mir immer wieder einen neuen Zugang zum Herrn zu verschaffen. Alle Morgen neu, w\u00e4hrend ich mich auf die Predigt vorbereite, suche ich nach M\u00f6glichkeiten, wie ich an den Herrn gelange. Auf meiner Homepage findest du eine F\u00fclle von Themen! Was mich besch\u00e4ftigt, predige ich. Das gebe ich weiter. Was mich bereichert hat, teile ich anderen Leuten mit, damit sie gesegnet werden. Nur das, was mich besch\u00e4ftigt hat, kann produziert werden. Ich gebe meine Erfahrungen weiter, runde die Themen ab und tauche tiefer in die jeweilige Thematik ein. Deshalb predige ich so lange! Es brennt mir auf dem Herzen! Das, was ich vom Herrn vernehme, gebe ich au\u00dferdem weiter. Bruder Otto, Schwester Helene haben eine F\u00fclle von Angeboten! Sie verf\u00fcgen \u00fcber eine gro\u00dfe Auswahl! Jede Predigt beinhaltet etwas Besonderes f\u00fcr dich! Auch die fr\u00fcheren Berliner Predigten von 1998 sind interessant! Ich beging Fehler und lernte daraus. Ich predige die Erkenntnis, welche ich daraus zog und sch\u00e4me mich nicht daran. Ich setze sie sinnvoll ein, um zu demonstrieren, wie man es <em>nicht<\/em> machen soll. Ich danke dem Herrn f\u00fcr meine Fehler und bekenne: \u201eLieber Gott, das ist der Mensch!\u201c Simon Petrus beging des \u00d6fteren Fehler! Er w\u00e4re anders niemals zu <em>dem<\/em> Petrus herangereift, der er wurde! Er lernte aus den Fehlern, die er beging! Mit Gottes Hilfe zeige ich, wie man es richtig und verkehrt macht. Ich kombiniere beides miteinander und demonstriere dadurch, wie man zu geistlicher Reife gelangt. Paulus sprach vor der Gemeinde zu Ephesus, wie nachfolgend geschrieben steht: <strong><u>Denn ich habe nichts verschwiegen, sondern habe euch den ganzen Ratschluss Gottes verk\u00fcndigt (Apg 20,27).<\/u><\/strong> Der Apostel weilte drei Jahre unter ihnen. Er brachte dieser Gemeinde den ganzen Ratschluss Gottes bei! Ich bin zehn Mal solange, also drei\u00dfig Jahre, in Berlin. Diese drei\u00dfig Jahre Predigtdienst haben mich gepr\u00e4gt. Paulus war blo\u00df drei Jahre in Ephesus und verk\u00fcndigte dort den ganzen Ratschluss des Herrn. Ich versuche desgleichen zu tun. Ob es verstanden wird oder nicht, interessiert mich kaum. Auch wenn ich nur in den Wind predigte, wei\u00df ich doch, was geschrieben steht. So spricht der Herr: <strong><u>Denn gleichwie der Regen und Schnee vom Himmel f\u00e4llt und nicht wieder dahin zur\u00fcckkehrt, sondern feuchtet die Erde und macht sie fruchtbar und l\u00e4sst wachsen, dass sie gibt Samen zu s\u00e4en und Brot zu essen,\u00a0so soll das Wort, das aus meinem Munde geht, auch sein: Es wird nicht wieder leer zu mir zur\u00fcckkommen, sondern wird tun, was mir gef\u00e4llt, und ihm wird gelingen, wozu ich es sende (Jes 55,10f.).<\/u>\u00a0<\/strong><\/p>\n<p>Reife und m\u00fcndige Christen haben den Heiligen Geist. Sie sollen h\u00f6ren, welche Botschaft der Geist des Herrn der Gemeinde mitteilt und was Gottes Geist durch die Verk\u00fcndigung spricht! Deshalb werbe ich f\u00fcr meine Predigten ganz intensiv und lasse es mich etwas kosten. Die Menschen m\u00fcssen Gottes Wort vernehmen! Das ist mein Hauptanliegen! Es geht nicht darum, in die Kirche zu gehen! Viele sitzen auf der Kirchbank und das Wort des Herrn gelangt nicht in ihr Inneres, weil sie zwar den Platz einnehmen, aber schl\u00e4frig werden. Verschlafe nicht das Wort des Herrn! Der Glaube kommt aus der Predigt und nicht aus dem Beten, Fasten, Singen, Jauchzen, Jodeln und Jubeln! Viele Christen meinen, dass das geistliche Leben aus Aktionen und gro\u00dfen Campagnen besteht. Nein!, es besteht aus der Predigt, w\u00e4hrend derer wir \u00fcber das Wort des Herrn nachsinnen. Ich will Gl\u00e4ubige zur geistlichen Reife f\u00fchren, motivieren und anstiften: H\u00f6re Gottes Wort! Ich gebe den Ratschluss des Herrn weiter! Zwischen siebenhundert bis tausendzweihundert Personen h\u00f6ren meine Predigten pro Tag. Manchmal sogar mehr, je nach dem, um welches Thema es sich dreht. Ich probiere in s\u00e4mtliche Kreise einzudringen. Denkt nicht, dass ich Unfug treibe. Es sind heute einige unter uns, die ich anders niemals erreicht h\u00e4tte als dadurch, mutig in der Berliner Zeitung zu werben. Bevor die Heilungsgottesdienste mit Billy Smith stattfanden, schaltete ich Anzeigen in der Esoterik-Szene frei! Scharen wurden auf diese Weise f\u00fcr Gott uns Sein Reich vereinnahmt! Ihr Glaube an den Herrn Jesus Christus wurde freigesetzt! Pl\u00f6tzlich merkten sie, dass Jesus verk\u00fcndigt wurde und nicht irgendein Heiler! Die Leute werden vom Heiligen Geist \u00fcberf\u00fchrt! Die Wahrheit macht sie frei! So spricht der Herr: <strong><u>Ihr werdet die Wahrheit erkennen, und die Wahrheit wird euch frei machen (Joh 8,32).<\/u> <\/strong>Ein Arzt brachte gleich zehn Personen in die Versammlung mit! Begeistert lie\u00df er Folgendes verlauten: \u201eHerr Matutis, das m\u00fcssen die Leute vernehmen!\u201c Wir m\u00fcssen den Mut aufbringen, in Feindesland bzw. in die H\u00f6lle zu gehen! Ich werbe bei Juden und Buddhisten! Mein Slogan lautet wie folgt: H\u00f6re Gottes Wort! Das ist neutral! Wir bezeugen und der Heilige Geist \u00fcberzeugt. Dabei ist es v\u00f6llig unerheblich, ob ich gerade eine Stra\u00dfenmission durchf\u00fchre und nicht wei\u00df, welche Passanten vor\u00fcberziehen und das Wort des Herrn vernehmen, oder ob ich von der Kanzel aus predige, w\u00e4hrenddessen es auf CD \u00fcbertragen und im Anschluss daran ausgestrahlt wird. Die Menschen entscheiden selbst, ob sie das Wort des Herrn annehmen wollen oder nicht.<\/p>\n<p>Ein alter Bruder sagte das Folgende: \u201eJohannes, bete nicht so viel, rede nicht so viel, sondern tue viel mehr! Du w\u00e4chst durch deine Taten!\u201c Das war mir eine starke Motivation, denn ich musste eigenverantwortlich agieren! So wurde ich reif durch die Gnade des Herrn! Mir wurde auf einmal bewusst, dass ich etwas tun musste, denn von Nichts kommt nichts! Seitdem bin ich in einem Entwicklungsprozess. Durch meine Taten wuchs und reifte ich heran. W\u00e4hrenddessen habe ich viele meiner geistlichen Kollegen abgeh\u00e4ngt, einzig und allein deshalb, weil ich tat, was der Herr mir befahl! Manchmal vielleicht etwas zu rasant, nicht genug ausgegoren, doch das ist egal, denn der Herr korrigiert uns und bringt uns auf den Boden der Tatsachen zur\u00fcck, gleichwie es Apostel Paulus widerfuhr: Wie bereits erw\u00e4hnt sprach er zuerst, dass er der beste Apostel w\u00e4re! Sp\u00e4ter verk\u00fcndigte er lauthals, dass er der gr\u00f6\u00dfte S\u00fcnder, welcher zahlreiche Fehler beging, ist! Von vielen Kollegen, die entweder mich nicht verstanden oder welche ich nicht verstand, verabschiedete ich mich. K\u00fcmmere dich nicht darum, ob Leute mit dir gehen oder nicht! Entscheidend ist, weiterzugehen und die Sache Gottes voranzutragen!<\/p>\n<p>Geistliche Reife entsteht, wenn man tut, was man tun sollte! Es ist das, was normal ist, was vor die H\u00e4nde kommt bzw. vor die F\u00fc\u00dfe geworfen wird. Suche dir nicht selbstst\u00e4ndig heraus, was zu tun ist! Wenn ich zu geistlicher Reife gelangen will, muss ich mir Ziele stecken und diese konsequent verfolgen! Reife Christen leben &#8218;von Jesus her&#8216;! Sie bewirken das, was Er bewirken w\u00fcrde. Die wichtigste Frage meines Lebens lautet wie folgt: \u201eWas w\u00fcrde Jesus tun?\u201c Das bewirkte den Wachstums- und Reifeprozess in mir. Einige Philosophien, Meinungen und Grunds\u00e4tze, die ich pers\u00f6nlich anwandte, da ich mir meiner Grenzen gewahr wurde, liste ich nachfolgend auf. Es ist m\u00f6glich sie zu kopieren, denn es besteht kein Copyright darauf!<\/p>\n<p>Ich tue nichts, wo ich merke, dass ich dem nicht gewachsen bin! Lass die Finger weg! Ich tue nur das, was ich mir zutraue und am besten vermag. Das ist keinesfalls alles, wie ich immer wieder betone! Ich bin kein Allround-Mensch und muss stets Priorit\u00e4ten setzen in meinem Leben. Das, was der Herr mir gegeben hat und was mir liegt, tue ich gern. Zum Beispiel predige ich Gottes Wort und verk\u00fcndige das Evangelium.<\/p>\n<p>Das N\u00e4chste, was ich gleich am Anfang meines Dienstes lernte, ist das Folgende: Zur Zeit, da ich noch ein junger Christ war, besuchte uns ein Pastor aus Kanada, der folgendes Wort predigte: \u201eLeute, h\u00f6rt auf euch mit anderen zu vergleichen! Jeder Mensch ist ein Original!\u201c Das wurde mir eingebl\u00e4ut, und das gebe ich hier weiter: Schaue nicht darauf, was die anderen tun! Du bist du! Tue das, was du als wichtig erkannt hast! Ich habe damit aufgeh\u00f6rt, mich zu vergleichen! Das war einer der wichtigsten Schritte f\u00fcr meine geistliche Reife! Ich schaute immer, wie weit diese oder jene bereits sind und sagte mir: \u201eWenn diese oder jene in den Himmel kommen, dann komme ich zweimal in den Himmel!\u201c Oder ich sprach: \u201eIst dieser \u00fcberhaupt ein Christ?\u201c Nun habe ich damit aufgeh\u00f6rt mich zu vergleichen! Ich bin zur Ruhe gelangt! Ich muss weder mit jemandem wetteifern noch jemandem beweisen, dass ich ein wunderbarer Christ, Apostel oder Heiliger bin. Nein! Genauso wenig, wie ich jemandem beweisen muss, dass ich ein S\u00fcnder bin. \u201eIch lebe konkurrenzlos und vergleiche mich mit niemandem!\u201c, verk\u00fcndigte dieser Pastor vor vielen Jahrzehnten, und: \u201eIch probiere, mein Leben nach dem Ma\u00df Gottes zu gestalten!\u201c<\/p>\n<p>Es geht mir auch nicht um Gemeindewachstum. Darauf war ich eine Zeit lang erpicht. Es gibt in Europa keine einzige Gemeindewachstumskonferenz, die ich nicht besucht h\u00e4tte! Birmingham sowie viele andere! S\u00e4mtliche Seminare besuchte ich, bis der liebe Gott zu mir sprach: \u201eJohannes, h\u00f6re doch auf damit Gemeindewachstum zu propagieren! Wachse <em>du<\/em>, dann w\u00e4chst die Gemeinde auch!\u201c Wie erreiche ich mehr Leute? Darum geht es mir nicht! Es geht mir weder darum, wie weit wir das Wort Gottes ausstrahlen noch darum, wie viele Predigten vorhanden sind! Es kommt einzig und allein darauf an, dass sich Wachstum und Reife an mir vollziehen. Der Herr wei\u00df, wer Gottes Wort aufnimmt und in die Ewigkeit forttr\u00e4gt. Wenn ich nur einer einzigen Person geholfen habe, stand ich der ganzen Menschheit bei. Das Gemeindewachstum interessiert mich nicht mehr, weil ich zu einem tiefen Frieden gelangt bin. Wie viele Menschen in meiner Gemeinde versammelt sind, interessiert mich nicht. Ich hatte gro\u00dfe, kleine und \u00fcberhaupt keine Gemeinden und war zufrieden. Das Reich Gottes ist inwendig in uns! Es ist nicht \u00c4u\u00dferlich vorhanden. (Siehe Lk 17,20f.) F\u00fcr mich war damals kein Weg zu weit, um Gemeindewachstum zu studieren. Zeitweise wuchs die Gemeinde rapide, sodass wir sogar Gelegenheit fanden zu studieren, <em>wie<\/em> das geschah, durch wen und warum. Das ist f\u00fcr mich uninteressant. Ich bin zur Ruhe gelangt und wei\u00df, dass ich nur meinem Gott diene, weder einer Organisation noch einer Gemeinde. Vor zwanzig Jahren verlie\u00df ich s\u00e4mtliche Organisationen. Du glaubst gar nicht, was in meinem Leben alles passierte: Ich habe bemerkt, dass ich ausgenutzt, verheizt, &#8218;an der Nase herum gef\u00fchrt&#8216; und erpresst wurde und sagte mir: \u201eNein, das ist nicht der Weg! Das ist nicht der Wille des himmlischen Vaters f\u00fcr mein pers\u00f6nliches Leben!\u201c Gott sprach: \u201eDiene allein mir und nicht dem Volk! Egal, was passiert, diene mir!\u201c Ich fing an, dem Herrn zu dienen. Ich wollte Gott gefallen und nicht irgendwelchen Leuten, Vorstehern, Geschwistern, Bekannten oder Freunden. Ich bin errettet, um dem lebendigen Gott zu Diensten zu stehen! Das steht in der Heiligen Schrift! Das proklamiere ich jetzt frei weg! Ich diene Jesus, der f\u00fcr mich starb. Ich habe eine Liebesbeziehung zu Jesus! Aber nicht nur das! Dadurch habe ich die Gegenwart des Herrn und des Heiligen Geistes in meinem Leben! Weil der Herr die Welt liebt, liebe ich pl\u00f6tzlich auch die anderen. Es hat \u00fcberhaupt keinen Wert der ganzen Welt zu helfen, den Fl\u00fcchtlingen, Armen usw., denn zuerst muss die Liebe des Herrn unsere Herzen erf\u00fcllen! Wenn das der Fall ist, geschieht das andere von selbst. Dann helfe ich automatisch meinem N\u00e4chsten. Dann gehe ich nicht an der Not des anderen vorbei. Dann wird der Herr mir schon die Person zeigen, welche &#8218;unter dem Kreuz liegt&#8216;. Was n\u00fctzt es, sich zu verausgaben, zu werkeln und voller Aktion zu sein? Nein!, der Herr will uns f\u00fchren!<\/p>\n<p>Ihr kennt die Geschichte aus der Heiligen Schrift, da Johannes und Petrus zur Gebetsstunde in den Tempel gehen. Dort sitzt eine lahme Person, welche die beiden um ein Almosen bittet. Das Folgende teilen sie ihr mit, wie geschrieben steht: <strong><u>Petrus aber sprach: Silber und Gold habe ich nicht; was ich aber habe, das gebe ich dir: Im Namen Jesu Christi von Nazareth steh auf und geh umher!\u00a0(Apg 3,6)<\/u><\/strong> Daraufhin geschieht Erweckung! Gemeindewachstum folgt! Es bekehren sich f\u00fcnftausend Leute! Wenn du richtig zum Herrn stehst und Ihn liebst, wirst du unweigerlich auch deinen N\u00e4chsten lieben und ihm dienlich sein! Jesus spricht: \u201eWer mich liebt, der tut, was ich sage; der h\u00f6rt auf die Stimme des Herrn!\u201c Der Herr will dich zur Reife bringen! Wir sollen unsere Gaben nicht nur dem Herrn, sondern der Menschheit zur Verf\u00fcgung stellen! Wenn du den Herrn liebst, dienst du nicht der Gemeinde, sondern der Menschheit! Du findest jemanden in der Nachbarschaft, dem du dienst bzw. eine Handreichung tust. Wir sind berufen, mit den Gaben, die der Herr uns zur Verf\u00fcgung stellte, unseren Mitmenschen dienlich zu sein! Da gibt es viel mehr, als diese in der Gemeinde. In der Gemeinde, ob gro\u00df oder winzig, kennst du h\u00f6chstens f\u00fcnf Personen richtig. Du glaubst gar nicht, wie einsam du in einer gro\u00dfen Gemeinde sein kannst! Ich war einer Gemeinde von neunhundert Mitgliedern zugeh\u00f6rig! Dort war ich einer von vielen und eine einsame Person! Erst in einer kleinen Gemeinde bekam ich zu sp\u00fcren, dass der Herr mich gebrauchen will! Dort lernte ich kranke und schwache Menschen kennen! Diese Personen fragte ich, ob ich f\u00fcr sie beten d\u00fcrfe. Keiner wird dir widersprechen, wenn du jemanden fragst, ob du f\u00fcr ihn beten darfst. Gott ist gut! Wo immer wir Menschen begegnen, dienen wir als Christen! Wir sind berufen, nicht der Kirche oder einer anderen Institution, Organisation oder Religion zu dienen, sondern dem Volk! In aller Liebe! Das Reich Gottes ist gr\u00f6\u00dfer als die gesamte Menschheit! Reife Christen bauen nicht ihr eigenes Reich, sondern das Reich Gottes! Wenn du voll des Heiligen Geistes bist, schaust du durch deinen Horizont. Du siehst viel mehr als nur deine Nachbarin. Wir hatten einen Bruder aus Bulgarien zu Besuch, der ein Zeugnis gab, welches mich stark inspiriert hatte: Er war in ein Hochhaus eingezogen, in dem einige hundert Leute wohnten. Folgendes betete er zum Herrn: \u201eO mein Gott, Du siehst, ich wohne in einem mehrst\u00f6ckigen Wohnhaus mit vielen Menschen, gib mir den Auftrag in diesem Geb\u00e4ude ein Missionar zu sein. Ich wollte schon immer ein Evangelist sein! Hier habe ich nun die Gelegenheit dazu!\u201c Er begann von oben nach unten zu missionieren, lud erst die eine und dann die andere Familie zu sich ein und erz\u00e4hlte ihnen seine Geschichte, warum er Christ sei usw. Nach kurzer Zeit war in seinem Haus ein Hauskreis versammelt. Das wurde seine eigene Gemeinde. So wurde er Pastor. Manche Leute denken, dass sie zuvor erst ordiniert werden m\u00fcssen. Du musst einfach nur damit beginnen, Gott und somit den Menschen zu dienen!<em> So<\/em> entsteht eine Gemeinde. Er hatte seine Gemeinde im eigenen Wohnhaus! Deshalb ist im Wort des Herrn Folgendes verzeichnet: \u201eUnd gr\u00fc\u00dfe diese, die in deinem Haus sind!\u201c Fange an, deinen Missionsauftrag in deiner Umgebung auszuf\u00fchren!<\/p>\n<p>Die Gemeinde eines bekannten koreanischen Pastors, der einen Auftrag f\u00fcr Tokio hatte, umfasste siebenhunderttausend Mitglieder. Folgendes Gebet tat er kund: \u201eLieber Gott, wie ist es m\u00f6glich die Japaner zu erreichen!\u201c Die Japaner sind sture Menschen; der Herr segne sie! Sie halten nichts von Christentum, kapseln sich ab und wollen ohne Gott sein. W\u00e4hrend er das Gebet sprach, gab der Herr ihm den folgenden Rat: \u201eNimm eine Schwester aus deiner Gemeinde. Deine Gemeinde w\u00e4chst und deren Gemeinden wachsen nicht. In mehr als einhundert Jahren wuchsen die Gemeinden h\u00f6chstens bis auf vierzig Personen an. Er wies ihn wie folgt an: \u201eBringe Gemeindewachstum nach Japan!\u201c Ein Missionar deiner Gemeinde soll die gleichen Prinzipien, welche in der diesigen Gemeinde vorherrschen, in Tokio umsetzen. Er suchte unter den Geschwistern die geeignete Person und erw\u00e4hlte einen Mann. Dieser widersetzte sich. Der Heilige Geist sprach: \u201eNimm eine Frau!\u201c Die Japaner glauben ohnehin nicht an Frauen. Er suchte sich die beste Hauskreisleiterin heraus, die ihm zur Verf\u00fcgung stand. Als sie ihm vorstellig wurde, fragte er sie: \u201eSchwester, bist du bereit nach Tokio zu gehen und nach unseren Prinzipien zu agieren?\u201c Sie erwiderte, dass sie den Herrn fragen werde. Er gab ihr gr\u00fcnes Licht. Ihr Pastor teilte ihr daraufhin Folgendes mit: \u201eWir zahlen dir nur ein Ein-Weg-Ticket! und, ich habe folgenden Wunsch: dass du in der Hauptstra\u00dfe von Tokio mit der Mission beginnst, wo sich die Gesch\u00e4ftsleute aufhalten. Sie mietete sich in einer Mansarde ein &#8211; f\u00fcr die erste Miete kam die Gemeinde auf &#8211; und betete zum Herrn folgendes Gebet: \u201eHier in dieser Gegend gibt es keine normalen Hausbewohner, sondern nur Gesch\u00e4ftsleute. Es ist nicht m\u00f6glich von Haus zu Haus zu gehen und zu missionieren. Herr, bitte stehe mir bei!\u201c Sie ging ins erste Gesch\u00e4ft und fragte den Gesch\u00e4ftsleiter, ob sie mit ihm beten d\u00fcrfe. Sie stellte sich vor und tat kund, dass sie eine Missionarin aus Korea sei. Dann fragte sie, ob sie ihn und sein Gesch\u00e4ft segnen d\u00fcrfe. Den Segen f\u00fchrte sie aus, notierte seine Daten und zog weiter. So arbeitete sie sich durch die ganze Allee. Nach einer Weile empfing sie das Wort vom Herrn, dass sie alle Gesch\u00e4ftsleute zu einer Konferenz einladen solle. Im Nu entstand eine Gemeinde von f\u00fcnfhundert Personen! Das geschah allein durch Gebet und die Arbeit im Untergrund. Wir denken, dass wir etwas Gro\u00dfes f\u00fcr den Herrn leisten und ein Stadion mieten m\u00fcssen. Nein! Gehe von Haus zu Haus! Beginne mit deinen Nachbarn zu beten. Du findest dadurch genug Kranke, Behinderte und Belastete.<\/p>\n<p>Reife Christen sind keine Massenchristen, sondern Einsiedler. Sie leben und vertrauen dem Herrn. Ein reifer Christ ist eine standfeste, stabile Person, die mit beiden Beinen im Leben steht. Sie stellt sich der Wirklichkeit. Der reife Christ h\u00e4lt Druck und Spannungen aus! Er hat einen festen Standpunkt, der auf folgenden Bibelvers gegr\u00fcndet ist: \u201eIch wei\u00df, dass mein Erl\u00f6ser lebt!\u201c (Siehe Hiob 19,25a) Er geht \u00fcberzeugt seinen Weg und wei\u00df, dass es keine Abk\u00fcrzung gibt! Er geht geradeaus den Weg, den Gott ihn f\u00fchrt und leitet, und l\u00e4sst sich nicht von \u00c4u\u00dferlichkeiten beeindrucken. Shadu Sunda Singh verfasste folgenden Song: \u201eIch bin entschieden zu folgen Jesus! Auch wenn niemand mit mir geht, ich gehe vorw\u00e4rts!\u201c Ein reifer Christ ist kein Kleinkind mehr. Manchmal wird er ein unbequemer Zeitgenosse. Er muss das eine oder andere Mal widersprechen und sagen: \u201eNein! Hier mache ich nicht mit!\u201c Da horchen die Leute auf und fragen: \u201eWarum macht er da nicht mit?\u201c Auch Absonderung geh\u00f6rt dazu! Er mischt nicht \u00fcberall mit; will nicht auf jeder Hochzeit die Braut und auf jeder Beerdigung die Leiche sein. Ihm geht es um Jesus und nicht um irgendwelche selbsternannten Messiasse. Es steht geschrieben: <strong><u>Wenn dann jemand zu euch sagen wird: Siehe, hier ist der Christus!, oder: Da!, so sollt ihr&#8217;s nicht glauben (Mt 24,23).<\/u><\/strong> Von wegen: \u201eHier ist Christus!\u201c, \u201eDa ist Christus!\u201c, \u201eDort ist Christus!\u201c Christus ist nirgendwo \u00e4u\u00dferlich vorhanden! Er ist in dir und sonst nirgends! In der Endzeit treten die selbsternannten Messiasse zutage! Das steht im Wort des Herrn. (Siehe Mt 24,24-26)<\/p>\n<p>Der reife Christ lebt in einer Vielfalt, nicht in einer Monokultur! Er lebt nach den Gesetzen und Geboten des Herrn! Er achtet strikt auf die F\u00fchrung Gottes: Heute dieses, morgen jenes usw. Er l\u00e4sst sich jeden Tag \u00fcberraschen. Monokultur f\u00fchrt nicht zur Reife! Ein reifer Christ blickt nach vorn. Er wei\u00df, dass er wenig wei\u00df, wie es Paulus bzw. sein Professor Gamaliel verlauten lie\u00df. Er wei\u00df, dass er noch viel zu wenig vom Herrn begriffen hat und tut folgende Worte kund: \u201eIch kenne zwar meinen himmlischen Vater, aber ich kenne ihn doch nicht.\u201c So erging es mir. Ich glaubte, ich w\u00e4re bereit zur Missionsarbeit und imstande, andere zu belehren. Ich druckte ein wunderbares Traktat in gr\u00fcner Farbe, das ich auf der Stra\u00dfe verteilte. Eine wahrscheinlich vom Herrn geschickte Person studierte aufmerksam das Traktat und gab es mir dankend mit folgenden Worten zur\u00fcck: \u201eBitte, mein Herr. Kennen <em>Sie<\/em> Jesus?\u201c Ich erwiderte: \u201eJa, ich bin Pastor und habe Theologie studiert und vieles mehr. Ich kenne mich aus und wei\u00df Bescheid!\u201c Zu Hause lag ich im Bett, wendete mich hin und her, schlief nicht ein und Gott sprach zu mir: \u201eJohannes, kennst du mich wirklich? Kennst du mich tats\u00e4chlich?\u201c Daraufhin musste ich Bu\u00dfe tun und sprach das folgende Gebet: \u201eLieber Heiland, ich kenne Dich, aber nicht so, wie ich Dich kennen sollte.\u201c Daraufhin begann ich zu fasten und den Herrn zu suchen. Ich schloss mich ein. Vielleicht muss dich auch jemand am Schopf nehmen und dir die folgende Mitteilung machen: \u201eKennen Sie Jesus?\u201c<\/p>\n<p>Was ist reifes Leben? Ein reifer Christ wei\u00df, dass er noch viel mehr vom Herrn ben\u00f6tigt! Demutsvoll begibt er sich auf die Knie und dennoch geht er vorw\u00e4rts! Im Neuen Testament ist Vollkommenheit ein Ziel und kein Stand! Die Richtung ist entscheidend! Paulus sprach, wie nachfolgend geschrieben steht:<strong> <u>Nicht, dass ich&#8217;s schon ergriffen habe oder schon vollkommen sei; ich jage ihm aber nach, ob ich&#8217;s wohl ergreifen k\u00f6nnte, weil ich von Christus Jesus ergriffen bin (Phil 3,12).<\/u><\/strong> Solches geschieht mit einem g\u00f6ttlichen Kleinod! Das vollkommene Leben ist ein zielbewusstes Dasein! Alle Morgen neu muss ich mich entscheiden, neu bekehren und Ihm die folgende Zusage erteilen: \u201eHeiland, diesen Tag will ich mit Dir nebst Deiner Hilfe und Kraft meistern!\u201c Das vollkommene Leben ist etwas entkrampftes und zielorientiertes! Entweder ich habe es erreicht oder nicht! Gegebenenfalls tue ich Bu\u00dfe. Manchmal vollende ich mein Tagwerk. Der verlorene Sohn kam nach Hause und wollte lediglich Tagel\u00f6hner sein. Er wollte nicht mehr &#8218;Sohn&#8216; hei\u00dfen. Den Tagesverdienst wollte er abends erhalten, Basta. Nicht meine Vergangenheit bestimmt mich, sondern das Ziel, welches ich verfolge: \u201eIch will Jesus sehen! Ich will das Ziel erreichen! Ich will meine Seligkeit!\u201c Als reifer Christ &#8218;halte ich in meiner Hand den Pflug und gehe neben dran&#8216;, auch wenn es manchmal schwierig ist. Ich habe meine Hand an den Pflug gelegt und ziehe sie nicht zur\u00fcck, bis ich den Acker gepfl\u00fcgt habe! Dasselbe Vorgehen wende ich bei meinen Themen an. Ich beackere sie und pfl\u00fcge sie durch. Manchmal ist der Boden steinig. Ich habe sowohl mit K\u00fchen als auch mit Pferden als auch mit einem Traktor gepfl\u00fcgt. Ich kenne mich mit dieser Arbeit aus und ben\u00f6tige keine Nachhilfe. Das ist knochenharte Arbeit.<\/p>\n<p>Ein reifer Christ ist f\u00e4hig zu unterscheiden. Es steht geschrieben:<strong> <u>Feste Speise aber ist f\u00fcr die Vollkommenen, die durch den Gebrauch ge\u00fcbte Sinne haben, Gutes und B\u00f6ses zu unterscheiden (Hebr 5,14).<\/u><\/strong> Er hat geschulte Sinne und wei\u00df, was richtig und was gut ist. Er hat ein geistliches Empfinden und wei\u00df, was richtig und was verkehrt ist, was wichtig und was unwichtig ist. Er unterscheidet Verpackung von Inhalt, Hauptsache von Nebensache. Ich habe gelernt, die Stimme des Herrn zu vernehmen und diese von der Stimme des Feindes zu unterscheiden! Nicht jede vernehmbare Stimme ist diese des Herrn! Die Stimme des Teufels ist zuweilen sehr stark. Ich musste pr\u00fcfen, wie es sich verh\u00e4lt! Ist es die Stimme des Herrn? Ich pr\u00fcfe sehr genau bevor ich Seine Anweisung, die ich vernommen habe, ausf\u00fchre! Mitunter lasse ich es mir mehrmals sagen und bitte den Herrn darum, es zu wiederholen, zuweilen bis zu zehn Mal! Erst dann werde ich gewahr: \u201eAha, das ist der Wille Gottes!\u201c<\/p>\n<p>Reife Christen nehmen nichts f\u00fcr selbstverst\u00e4ndlich. Sie ben\u00f6tigen nicht nur &#8218;Milch, sondern feste Kost&#8216;. Ein reifer Christ ging durch Pr\u00fcfungen hindurch und blieb standhaft. Er bew\u00e4hrte sich in Anfechtungen und &#8218;zerbrach&#8216;. Wer will schon das? Er zerbrach, blieb standhaft und bew\u00e4hrte sich! Zerbrochenheit f\u00fchrt zur Reife! Solange du nicht zerbrochen wurdest, Bruder und Schwester, bist du nicht reif f\u00fcr die Reife! Es steht geschrieben: <strong><u>Meine Br\u00fcder und Schwestern, erachtet es f\u00fcr lauter Freude, wenn ihr in mancherlei Anfechtung fallt,\u00a0und wisst, dass euer Glaube, wenn er bew\u00e4hrt ist, Geduld wirkt.\u00a0Die Geduld aber soll zu einem vollkommenen Werk f\u00fchren, damit ihr vollkommen und unversehrt seid und keinen Mangel habt (Jak 1,2-4).<\/u><\/strong> Angriffe, Schmerzen, Krisen u.\u00c4. f\u00fchren zur Reife hin! Anfechtungen sind da, damit wir die Probleme l\u00f6sen und nicht nur weg beten! H\u00f6rt doch auf! Ich bete nicht mehr weg! Ich l\u00f6se das, was auf mich zukommt! Weg-zu-Beten hilft nicht! Gestern sprach ich \u00fcber Krankheit. Krankheit ist ein Geist, ein D\u00e4mon! Krankheit ist eine Sprache des K\u00f6rpers, die du verstehen musst, damit das Problem weicht! Vergib und die Heilung setzt ein!<\/p>\n<p>Ein reifer Christ liebt bedingungslos seine Feinde! Vermagst du deine Feinde zu lieben? So kl\u00e4rst du die Frage, ob du schon ein reifer Christ bist selbst. Ich werde niemals folgende Situation vergessen, die ich in meiner damaligen Br\u00fcdergemeinde mit evangelikaler Ausrichtung erfuhr: Ein Bruder erhob sich und lie\u00df Folgendes verlauten: \u201eIch kann nur diese lieben, welche mir sympathisch sind!\u201c Diese zu lieben, welche &#8218;auf deiner Wellenl\u00e4nge sind&#8216;, den gleichen Geist und dieselbe Chemie haben, ist keine Kunst! Das vermag der Teufel auch! Das ist \u00fcberhaupt kein Problem! Daf\u00fcr ben\u00f6tigt man weder Gnade noch Heiligen Geist. Diese Person war wenigstens ehrlich und stand dazu! Es steht geschrieben: <strong><u>\u00dcber alles aber zieht an die Liebe, die da ist das Band der Vollkommenheit (Kol 3,14).<\/u><\/strong> Paulus nennt die Liebe das Band der Vollkommenheit! Ein Kennzeichen geistlicher Reife ist, dass du genie\u00dfbar bist, sodass man gern mit dir umgeht. Unreife Fr\u00fcchte sind bitter, hart und giftig. Sie schmecken nicht. Wir sollen als Christen einen lieblichen Geruch Jesu Christi ausstrahlen. Wenn wir mit Jesus verbunden sind, sind wir genie\u00dfbar und essbar und &#8218;wir werden vernascht&#8216;. Viele Menschen denken, dass das Hauptmerkmal der geistlichen Reife ein gro\u00dfer Glaube ist, sprich, dass es gelingt, gro\u00df zu glauben und &#8218;Berge zu versetzen&#8216;. So spricht der Herr:<strong> <u>Wenn ich mit Menschen- und mit Engelzungen redete und h\u00e4tte der Liebe nicht, so w\u00e4re ich ein t\u00f6nendes Erz oder eine klingende Schelle (1 Kor 13,1).<\/u><\/strong>\u00a0Liebe ist das Gr\u00f6\u00dfte und nicht der Glaube! (Siehe Gal 5,6) Die Bibel lehrt, dass der Glaube durch die Liebe wirksam wird! Die Liebe aktiviert den Glauben und setzt ihn in Kraft! Ohne Liebe n\u00fctzt alles nichts: weder Glauben noch Zungenreden noch Zitieren noch Proklamieren, einfach gar nichts! Beim Herrn z\u00e4hlen die Taten und nicht die Worte! Glaube ohne Liebe ist wie eine Taschenlampe ohne Batterie!<\/p>\n<p>Welche Schritte zur geistlichen Reife m\u00fcssen wir vollziehen? Werdet m\u00e4nnlich und stark!, teilt uns die Heilige Schrift mit. (Vgl. 1 Kor 16,13b) Das bezieht sich auch auf die Frauen! Nicht nur die M\u00e4nner sollen stark werden! Die meisten M\u00e4nner sind nicht mehr m\u00e4nnlich! Tut mir leid, dass ich das verlauten lassen muss. Sie wurden von unserer Gesellschaft impotent gemacht. Doch in der Bibel steht: Werdet m\u00e4nnlich und stark! Wie funktioniert M\u00e4nnlichkeit? Unsere Gesellschaft ist weibisch geworden. Uns fehlen Mannsbilder. Tut mir leid, dass sich das so verh\u00e4lt in der Gemeinde bzw. im Reich Gottes! Was versteht die Bibel unter M\u00e4nnlichkeit? Echte M\u00e4nner scheitern nicht! Sie halten durch und stehen ihren Mann an dem Platz, wo sie hingestellt wurden. M\u00e4nner geben nicht auf! Sie kapitulieren nicht! Ich spreche von M\u00e4nnern. Frauen tun nicht dergleichen. Entschuldigung! Frauen sehnen sich nach echten M\u00e4nnern, die zu ihrer Sache stehen und nicht verweichlicht sind. Sie gehen hart an die Sache, was es auch immer sein mag. Was ist echte M\u00e4nnlichkeit? Lies den Sch\u00f6pfungsbericht! Gott schuf den Mann ganz am Anfang! Der Mann ist gleich dem Bilde Gottes kreiert worden! Er soll den Herrn repr\u00e4sentieren! Seid m\u00e4nnlich und stark! Als reifer Christ sollst du ein Repr\u00e4sentant des Herrn sein, da, wo du stehst! Ein Stellvertreter des Allm\u00e4chtigen auf Erden ist nicht der Papst im Vatikan, sondern du und ich sowie jede Person, die an den Herrn Jesus Christus gl\u00e4ubig wurde!<\/p>\n<p>Ihr Stellvertreter Jesu! Wir sind Gottes Ebenbilder! Wir sollen Priester im Hause des Herrn sein! Hat sich der Ehemann dem Herrn untergeordnet, ist es f\u00fcr seine Frau kein Problem, ihn zu akzeptieren. Ordnet sich die Ehefrau dem Mann unter nach der biblischen Reihenfolge, ist es f\u00fcr die Kinder einfach, die Mutter zu akzeptieren. \u201eWas will der Alte bzw. die Alte!\u201c, sagen Kinder heutzutage \u00fcber ihre Eltern! M\u00e4nner, die sich dem Herrn nicht unterstellen, sind &#8218;Waschlappen&#8216;! Tut mir leid, dass ich das sagen muss! Echte M\u00e4nner haben den Charakter des Herrn! Sie tragen die g\u00f6ttliche DNA in sich und besitzen die g\u00f6ttlichen Eigenschaften! Sie sind dem Herrn wohlgef\u00e4llig! Darauf gehe ich ein. Das Wort des Herrn, welches gem\u00e4\u00df der \u00dcberlieferung aus der Heiligen Schrift offenbar wurde und nachfolgend niedergeschrieben steht, lautet wie folgt: <strong><u>Dann sprach Gott: Lasst uns Menschen machen als unser Bild, uns \u00e4hnlich! Sie sollen walten \u00fcber die Fische des Meeres, \u00fcber die V\u00f6gel des Himmels, \u00fcber das Vieh, \u00fcber die ganze Erde und \u00fcber alle Kriechtiere, die auf der Erde kriechen (1 Mose 1,26).<\/u><\/strong>\u00a0Du sollst \u00fcber solches alles Herr sein! Diese Worte verk\u00fcndigte der himmlische Vater. Beherrsche deine Situation! Beherrsche dich selbst! Wir sollen heilig sein wie der Herr! Wir sind eine besondere Sch\u00f6pfung! Gottes Wort zeigt, was echte M\u00e4nnlichkeit ist: es ist Gott\u00e4hnlichkeit! Alles andere ist Unfug! Wo triffst du heutzutage noch Menschen, die dem Herrn gleichen? Die Kirche lehrt es nicht!<\/p>\n<p>Wir sind geschaffen, um mit dem Herrn Gemeinschaft auszu\u00fcben! Der himmlische Vater wollte mit Seiner Kreatur kommunizieren! Es steht geschrieben: <strong><u>Gott segnete sie und Gott sprach zu ihnen: Seid fruchtbar und mehrt euch, f\u00fcllt die Erde und unterwerft sie und waltet \u00fcber die Fische des Meeres, \u00fcber die V\u00f6gel des Himmels und \u00fcber alle Tiere, die auf der Erde kriechen! (1 Mose 1,28)<\/u><\/strong> Echte, reife Christen nehmen die Worte des Herrn wahr! Das Folgende ist der erste Bericht \u00fcber die Gemeinschaft mit dem Herrn: \u201eSei gesegnet!\u201c Diese Worte sprach der himmlische Vater! Wenn du gesegnet bist, tust du das, was der Herr dir gebietet! M\u00e4nnlichkeit ist, auf Gott zu h\u00f6ren! D.h., Gottes Wort sich zu Herzen zu nehmen und darin zu bewegen sowie mit dem Herrn zu kommunizieren und Seinen Willen zu tun! Wenn das Fundament nicht stimmt, ist der ganze Bau schief und schr\u00e4g! Ich denke nur an den Turm von Pisa. Da ist alles schief und schr\u00e4g! Du kannst von unten st\u00fctzen soviel du willst, es geschieht nichts! Um zu reifen brauchen wir &#8218;ein gesundes Wurzelwerk&#8216;. Das will uns der Herr verleihen! Wir ben\u00f6tigen den Geist des himmlischen Vaters bzw. den Heiligen Geist, damit wir richtige Menschen werden! \u00dcber K\u00f6nig Saul, der einem Esel nachlief, ist einmal Folgendes notiert. Es steht geschrieben: <strong><u>Wenn nun der Geist Gottes \u00fcber Saul kam, nahm David die Harfe und spielte darauf mit seiner Hand. So erquickte sich Saul, und es ward besser mit ihm, und der b\u00f6se Geist wich von ihm (1 Sam 16,23).<\/u><\/strong> Wenn der Heilige Geist \u00fcber dein Leben kommt, wirst du eine andere Frau bzw. ein anderer Mann! Seid m\u00e4nnlich und stark!, steht in der Heiligen Schrift! Wir haben Verantwortung zun\u00e4chst einmal f\u00fcr uns selbst, f\u00fcr diese Erde und f\u00fcr das Umfeld, in dem wir leben bzw. die Sch\u00f6pfung! Wir d\u00fcrfen nicht leichtfertig sein! Der Mensch Adam sollte f\u00fcr die Tiere einen Namen finden! Er sollte sich Namen ausdenken. Ein paar Ver\u00e4nderungen sind ersichtlich, ansonsten haben diese Namen bis zum heutigen Tage Bestand! Der Mensch war dazu befugt, denn er besa\u00df Einsicht, Weisheit, Erkenntnis und Wissen! Doch w\u00e4hrend dieser Pr\u00fcfung fiel der Mensch durch! Er verlor seine Autorit\u00e4t, St\u00e4rke, Macht und M\u00e4nnlichkeit! Das ereignete sich im Paradies, weil Eva Adam die Frucht reichte! Das Wort des Herrn, welches gem\u00e4\u00df der \u00dcberlieferung aus der Heiligen Schrift offenbar wurde und nachfolgend niedergeschrieben steht, lautet wie folgt: <strong><u>Und Gott der HERR nahm den Menschen und setzte ihn in den Garten Eden, dass er ihn bebaute und bewahrte (1 Mose 2,15).<\/u><\/strong> Der Herr gab dem Menschen einen bestimmten Daseinszweck, damit er sich verwirklicht, das Paradies ausbaut und \u00fcber das ganze Erdreich bringt! Doch was tat er? Er wurde aus dem Paradies verjagt! Dornen und Disteln sollten nunmehr auf seinem Wege wachsen! Kennst du, kenne ich, kennen wir den Zweck unseres Daseins? Entwickeln wir uns schon in die richtige Richtung? Das ist f\u00fcr mich geistliche Reife: Lasset uns Menschen machen! Viele entwickeln sich zum Nachteil. Sie werden nicht m\u00e4nnlich und stark, sondern Weichlinge, Schw\u00e4chlinge und Feiglinge, die zu nichts mehr n\u00fctze sind! Entschuldige bitte, aber das ist der heutige Lauf der Dinge. Der Prophet Jesaja weissagte vor zweitausendf\u00fcnfhundert Jahren das folgende Wort: So spricht der Herr: <strong><u>Kinder unterdr\u00fccken mein Volk, Frauen beherrschen es. O mein Volk, deine Herrscher verf\u00fchren dich! Sie vernebeln den Weg, den du gehen sollst (Jes 3,12).<\/u><\/strong> Weiber und Kinder werden das Land regieren! Das geschieht vor unseren Augen! Sieh es dir an: Alle Regierungen haben Frauen als Pr\u00e4sidentinnen oder Kanzlerinnen. Kinder veranstalten Massendemonstrationen, um die Regierung zu beeinflussen. Wir sind mitten in der Endzeit! \u00d6ffne deine Augen! Schalte deinen Fernseher ein! Lies die Propheten sowie die Geschichtsb\u00fccher!<\/p>\n<p>Kommuniziert der Mensch mit dem himmlischen Vater, wird er der Absichten Gottes gewahr! Dessen Leben wird ein erf\u00fclltes und gesegnetes werden. Wir wurden geschaffen, um das Werk des Herrn fortzusetzen, uns zu vermehren sowie uns die Erde untertan zu machen! Wenn ich die Bibel richtig studiere, verstehe ich, was M\u00e4nnlich-Sein hei\u00dft: Einerseits das Werk des Herrn fortzusetzen und andererseits die Welt zu kultivieren! Wir sollen der Welt Kultur beibringen und ihr kundtun, wie man als Christ lebt! Wir sind nicht dazu angelegt die Welt zu kopieren, sondern dazu, dass die Welt uns kopiert! Wir sollen eine solche Ausstrahlung haben und entsprechende Impulse geben, damit die Welt lernt! Wir sollen uns verbessern und vermehren! Christen sollen auf andere Leute ansteckend wirken! Wir sollen &#8218;Brandstifter&#8216; und fruchtbar sein! Das hat nichts damit zu tun, Kinder in die Welt zu setzen, sondern damit, geistliche Funktionen zu \u00fcbernehmen! Wir sollen das Wachstum vorantreiben und uns die \u00e4u\u00dferen Dinge untertan machen! Nicht du sollst beherrscht werden, sondern selbst die Herrschaft aus\u00fcben, \u00fcber wen oder was auch immer! Du sollst herrschen! Du sollst die Plantage des Herrn besch\u00fctzen und bewachen und ihr keinen Schaden zuf\u00fcgen! Das Reich des Herrn, die Wahrheit und das Richtige zu verteidigen ist unser Metier! Es gibt genug Angreifer, die die Sache des Herrn antasten und zunichte machen wollen! Es gibt gen\u00fcgend Feinde! Eine echte M\u00e4nnlichkeit ist ein Gebot des Herrn! \u201eSeid m\u00e4nnlich und stark!\u201c, sprach der Herr! Wollen wir das \u00fcberhaupt? Du denkst: \u201eJa, da muss ich etwas tun!\u201c Echte reife Christen sind begabt wie Adam! Sie finden die Namen f\u00fcr die Tiere heraus und sagen: \u201eDas ist ein L\u00f6we, ein Affe oder ein Schwein!\u201c Bei dem Schwein wusste er wahrscheinlich nicht einmal, worum es sich dabei handelte, aber er gab den Namen, sowie Tiger, Katze, Hund, Vogel u.a. Er verlieh dem Geschaffenen Namen. Der Name macht das Ganze aus!, was auch immer das bedeutet; das ist eine Predigt f\u00fcr sich selbst. Der Herr gab Adam Verantwortung \u00fcber jedes Lebewesen, damit er diesem einen Namen zu verleihen vermochte. Heute will der Herr jeden Einzelnen mit der Gabe der Erkenntnis beschenken, sodass er imstande ist, das Tier beim Namen zu nennen! \u201eDas ist ein L\u00f6we!\u201c<\/p>\n<p>Der Herr gab uns Gaben zu einem ganz bestimmten Zweck und f\u00fcr eine ganz bestimmte Aufgabe. Bei Ihm ist jede Person individuell! Bist du geistlich reif? Reifst du, dass du pl\u00f6tzlich zur Erkenntnis gelangst und Dinge siehst, die du vorher nicht wahrnahmst? Die Leute um dich herum, werden dich nicht verstehen. Sie denken, dass du ein Wahrsager, Hellseher o.\u00c4. bist. Aber genau das geschieht, wenn du mit dem Herrn wandelst und Ihn in alles einbeziehst. Du bist ein Hell-Seher, der erkennt, wie die Dinge wirklich sind. Du erf\u00fcllst deinen Zweck, deine Bestimmung und Erw\u00e4hlung. Reifst du wirklich? Bist du geistlich reif? Bist du in einem Reifungsprozess? Im Gegensatz zu Israel ist Moab nie &#8218;umgesch\u00fcttet&#8216; worden. Das ist das Bild vom Wein und den Trauben. Aber Israel wurde ver\u00e4ndert, vertrieben, eingesetzt, wieder ver\u00e4ndert, wieder vertrieben und wieder eingesetzt! Es erlebte zahlreiche Ver\u00e4nderungen, aber Moab blieb stehen und unver\u00e4ndert! Die Hefe setzte sich unten ab und der Wein reifte nicht. (Siehe Jer 48,11) Wir reifen nicht, wenn wir auf dem sitzenbleiben, was wir haben und nach jener Devise Worte wie die folgenden kundtun: \u201eIch habe den Herrn erfahren! Ich bin christlich! Ich bin evangelisch! Ich bin katholisch! Ich glaube an Gott!\u201c Nein! Die st\u00e4ndige Ver\u00e4nderung, sprich, mal dieses und mal jenes, mal hoch und mal tief, <em>das<\/em> macht den Unterschied! Israel wurde umgest\u00fclpt! Es war nicht Moab gleich!, steht in der Heiligen Schrift. Es war fortw\u00e4hrend in einem Lernprozess, sowie wir Christen auch! Der Herr l\u00e4sst zu, dass du in bestimmte Situationen ger\u00e4tst, damit du wachger\u00fcttelt wirst, dich umblickst und schaust, wo du dich \u00fcberhaupt befindest. Pl\u00f6tzlich erschrickst du, doch du hast die M\u00f6glichkeit dich zu ver\u00e4ndern! Solang du lebst ist es m\u00f6glich sich zu ver\u00e4ndern! Die meisten Christen stagnieren. Stell dir nur mal vor, ich w\u00fcrde mit dem Fahrrad in die Gemeinde fahren, mich bewegen und vorw\u00e4rts schreiten. Ich w\u00fcrde nach links oder rechts umkippen. So verh\u00e4lt es sich bei vielen Christen. Sie fielen ins Extrem, entweder nach links oder nach rechts, aus folgendem Grund: sie bewegen und ver\u00e4ndern sich nicht. Solange du in Bewegung bleibst ist es m\u00f6glich, dass Ziel deines Lebens zu ver\u00e4ndern! Erkenne, was der Herr in deinem Leben tun m\u00f6chte!<\/p>\n<p>Jesus ist unser Vorbild! Er wollte nicht am Kreuz sterben! Der Heiland war auch ein Feigling. Im Garten Gethsemane rang Er und schwitzte Blut und Wasser. Es steht geschrieben: <strong><u>Und er ging ein wenig weiter, fiel nieder auf sein Angesicht und betete und sprach: Mein Vater, ist&#8217;s m\u00f6glich, so gehe dieser Kelch an mir vor\u00fcber; doch nicht, wie ich will, sondern wie du willst! (Mt 26,39)<\/u><\/strong> Er stimmte Seinem himmlischen Vater zu! Wir m\u00fcssen um zu reifen dem Herrn zustimmen und folgendes Zugest\u00e4ndnis machen: \u201eJa, Herr! Dein Wille geschehe!\u201c Dadurch werden wir in die Lage versetzt, unser Leben zu gestalten! Dadurch wachsen wir! Schwierige Zeiten werden kommen, denn sie m\u00fcssen bew\u00e4ltigt werden! Halleluja! Der Herr m\u00f6ge uns beistehen, dass wir reifen in den Schwierigkeiten, N\u00f6ten und \u00c4ngsten! David wurde stark durch die N\u00f6te und seine vollzogenen K\u00e4mpfe! Auf <em>diesem<\/em> Weg wirst du reif! Ich will dich nicht gesund beten. Du solltest durch diese Krankheit hindurchgehen und lernen, zu erstarken an der inwendigen Person.<\/p>\n<p><strong><u>Gebet:<\/u><\/strong><\/p>\n<p>Lieber Heiland, ich danke Dir, dass Du wei\u00dft, wie viel Tiefs wir durchmachen m\u00fcssen und was in unserem Leben alles passiert und geschieht! Ich danke Dir von ganzem Herzen, Herr Jesus, dass auch ich jeden Tag ringen muss gleichwie Du es tatest im Garten Gethsemane, als Du sprachst: \u201eHerr, Dein Wille geschehe!\u201c Nicht was ich will, sondern was Du willst m\u00f6ge geschehen, damit ich reife, um das Ziel meiner Berufung und Erw\u00e4hlung zu erreichen! Himmlischer Vater, ich segne alle meine Geschwister, die jetzt durch viele Tiefs gehen, die viele Dinge nicht verstehen, die noch unreif bzw. Kinder sind, die noch niemals nahrhafte Kost genossen haben, damit sie inwendig stark sind! \u00d6ffne ihnen die Augen, damit sie erkennen, um was es wirklich geht! Ich habe bezeugt und Du, lieber Heiliger Geist, \u00fcberzeuge! Ich danke Dir von ganzem Herzen! Du wei\u00dft, was f\u00fcr uns am besten ist, was f\u00fcr mich das Beste ist, und ich wei\u00df Folgendes: Denen, die Gott lieben, dienen alle Dinge zum Besten. Amen<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Seid m\u00e4nnlich und stark, echte M\u00e4nnlichkeit ist Gott\u00e4hnlichkeit.<\/p>\n","protected":false},"author":2,"featured_media":4337,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12,17,2],"tags":[501,235,497,499,500,498,324,700],"class_list":["post-542","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-j-w-matutis","category-mitschrift","category-predigt","tag-bist-du","tag-du","tag-geistlich","tag-geistliche-reife","tag-reif-sein","tag-reife","tag-sein","tag-zipfel","comments-off"],"_links":{"self":[{"href":"https:\/\/berliner-predigten.de\/blog\/wp-json\/wp\/v2\/posts\/542","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/berliner-predigten.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/berliner-predigten.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/berliner-predigten.de\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/berliner-predigten.de\/blog\/wp-json\/wp\/v2\/comments?post=542"}],"version-history":[{"count":9,"href":"https:\/\/berliner-predigten.de\/blog\/wp-json\/wp\/v2\/posts\/542\/revisions"}],"predecessor-version":[{"id":9444,"href":"https:\/\/berliner-predigten.de\/blog\/wp-json\/wp\/v2\/posts\/542\/revisions\/9444"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/berliner-predigten.de\/blog\/wp-json\/wp\/v2\/media\/4337"}],"wp:attachment":[{"href":"https:\/\/berliner-predigten.de\/blog\/wp-json\/wp\/v2\/media?parent=542"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/berliner-predigten.de\/blog\/wp-json\/wp\/v2\/categories?post=542"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/berliner-predigten.de\/blog\/wp-json\/wp\/v2\/tags?post=542"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}