{"id":27319,"date":"2025-04-05T20:20:35","date_gmt":"2025-04-05T18:20:35","guid":{"rendered":"https:\/\/berliner-predigten.de\/blog\/?p=27319"},"modified":"2025-04-06T00:00:03","modified_gmt":"2025-04-05T22:00:03","slug":"wiederhole-deine-fehler-nicht","status":"publish","type":"post","link":"https:\/\/berliner-predigten.de\/blog\/2025\/04\/05\/wiederhole-deine-fehler-nicht\/","title":{"rendered":"Wiederhole deine Fehler nicht"},"content":{"rendered":"<p>Also sowas passiert mir nicht. Fehler sind keine S\u00fcnde.<\/p>\n<audio class=\"wp-audio-shortcode\" id=\"audio-27319-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/berliner-predigten.de\/dateien\/2025-04-05-Wiederhole-deine-Fehler-nicht.mp3?_=1\" \/><a href=\"https:\/\/berliner-predigten.de\/dateien\/2025-04-05-Wiederhole-deine-Fehler-nicht.mp3\">https:\/\/berliner-predigten.de\/dateien\/2025-04-05-Wiederhole-deine-Fehler-nicht.mp3<\/a><\/audio>\n<p><!--more--><\/p>\n<div style=\"width: 640px;\" class=\"wp-video\"><video class=\"wp-video-shortcode\" id=\"video-27319-1\" width=\"640\" height=\"360\" preload=\"metadata\" controls=\"controls\"><source type=\"video\/mp4\" src=\"https:\/\/video-predigten.de\/2025\/250405-Wiederhole-deine-Fehler-nicht.mp4?_=1\" \/><a href=\"https:\/\/video-predigten.de\/2025\/250405-Wiederhole-deine-Fehler-nicht.mp4\">https:\/\/video-predigten.de\/2025\/250405-Wiederhole-deine-Fehler-nicht.mp4<\/a><\/video><\/div>\n<p><strong>Stichworte:<\/strong> ein St\u00fcck Seelsorge, der Umgang mit eigenen und fremden Fehlern &#8211; Vergeben und Vergessen &#8211; <a href=\"https:\/\/berliner-predigten.de\/blog\/2019\/11\/24\/der-gockel-von-kuenzelsau\/\" target=\"_blank\" rel=\"noopener\">der Gockel von K\u00fcnzelsau<\/a> &#8211; <a href=\"https:\/\/berliner-predigten.de\/blog\/2025\/04\/04\/die-wahrheit-wird-siegen\/\" target=\"_blank\" rel=\"noopener\">die Wahrheit wird siegen<\/a> &#8211; Ausrutscher, Missgriffe und Irrt\u00fcmer &#8211; Lieblosigkeit gegen sich selbst &#8211; ein Verh\u00e4ltnis der Liebe<\/p>\n<p>Wer uns unterst\u00fctzen m\u00f6chte, kann dies hier tun: <a href=\"https:\/\/berliner-predigten.de\/blog\/spenden\/\" target=\"_blank\" rel=\"noopener noreferrer\">\u2665 Spenden \u2665<\/a><\/p>\n<p><strong><em>Predigt herunterladen:<\/em><\/strong><br \/>\n<em>Audio <a href=\"https:\/\/berliner-predigten.de\/dateien\/2025-04-05-Wiederhole-deine-Fehler-nicht.mp3\" target=\"_blank\" rel=\"noopener noreferrer\">2025-04-05 Wiederhole deine Fehler nicht<\/a><\/em><br \/>\n<em>Video <a href=\"https:\/\/video-predigten.de\/2025\/250405-Wiederhole-deine-Fehler-nicht.mp4\" target=\"_blank\" rel=\"noopener\">Wiederhole deine Fehler nicht<\/a><\/em><\/p>\n<p><a href=\"https:\/\/berliner-predigten.de\/blog\/wp-content\/uploads\/2025\/04\/250405-also-sowas-passiert.webp\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-27329 size-medium\" src=\"https:\/\/berliner-predigten.de\/blog\/wp-content\/uploads\/2025\/04\/250405-also-sowas-passiert-300x300.webp\" alt=\"Also sowas passiert mir nicht\" width=\"300\" height=\"300\" srcset=\"https:\/\/berliner-predigten.de\/blog\/wp-content\/uploads\/2025\/04\/250405-also-sowas-passiert-300x300.webp 300w, https:\/\/berliner-predigten.de\/blog\/wp-content\/uploads\/2025\/04\/250405-also-sowas-passiert-150x150.webp 150w, https:\/\/berliner-predigten.de\/blog\/wp-content\/uploads\/2025\/04\/250405-also-sowas-passiert-768x768.webp 768w, https:\/\/berliner-predigten.de\/blog\/wp-content\/uploads\/2025\/04\/250405-also-sowas-passiert.webp 949w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Also sowas passiert mir nicht. Fehler sind keine S\u00fcnde.<\/p>\n","protected":false},"author":2,"featured_media":27320,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12,2,1434],"tags":[2373,356,2372],"class_list":["post-27319","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-j-w-matutis","category-predigt","category-video","tag-deine-fehler","tag-fehler","tag-nicht-wiederholen","comments-off"],"_links":{"self":[{"href":"https:\/\/berliner-predigten.de\/blog\/wp-json\/wp\/v2\/posts\/27319","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/berliner-predigten.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/berliner-predigten.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/berliner-predigten.de\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/berliner-predigten.de\/blog\/wp-json\/wp\/v2\/comments?post=27319"}],"version-history":[{"count":12,"href":"https:\/\/berliner-predigten.de\/blog\/wp-json\/wp\/v2\/posts\/27319\/revisions"}],"predecessor-version":[{"id":27334,"href":"https:\/\/berliner-predigten.de\/blog\/wp-json\/wp\/v2\/posts\/27319\/revisions\/27334"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/berliner-predigten.de\/blog\/wp-json\/wp\/v2\/media\/27320"}],"wp:attachment":[{"href":"https:\/\/berliner-predigten.de\/blog\/wp-json\/wp\/v2\/media?parent=27319"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/berliner-predigten.de\/blog\/wp-json\/wp\/v2\/categories?post=27319"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/berliner-predigten.de\/blog\/wp-json\/wp\/v2\/tags?post=27319"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}