{"id":26895,"date":"2025-02-22T17:53:59","date_gmt":"2025-02-22T16:53:59","guid":{"rendered":"https:\/\/berliner-predigten.de\/blog\/?p=26895"},"modified":"2025-02-22T22:52:47","modified_gmt":"2025-02-22T21:52:47","slug":"vorteile-der-vergebung","status":"publish","type":"post","link":"https:\/\/berliner-predigten.de\/blog\/2025\/02\/22\/vorteile-der-vergebung\/","title":{"rendered":"Vorteile der Vergebung"},"content":{"rendered":"<p>Deine Vergangenheit ist ausgel\u00f6scht, du kannst wieder bei Null anfangen. Es geht um dein Wohl. Hast du den inneren Frieden?<\/p>\n<audio class=\"wp-audio-shortcode\" id=\"audio-26895-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/berliner-predigten.de\/dateien\/2025-02-22-Vorteile-der-Vergebung.mp3?_=1\" \/><a href=\"https:\/\/berliner-predigten.de\/dateien\/2025-02-22-Vorteile-der-Vergebung.mp3\">https:\/\/berliner-predigten.de\/dateien\/2025-02-22-Vorteile-der-Vergebung.mp3<\/a><\/audio>\n<p><!--more--><\/p>\n<div style=\"width: 640px;\" class=\"wp-video\"><video class=\"wp-video-shortcode\" id=\"video-26895-1\" width=\"640\" height=\"360\" preload=\"metadata\" controls=\"controls\"><source type=\"video\/mp4\" src=\"https:\/\/video-predigten.de\/2025\/250222-Vorteile-der-Vergebung.mp4?_=1\" \/><a href=\"https:\/\/video-predigten.de\/2025\/250222-Vorteile-der-Vergebung.mp4\">https:\/\/video-predigten.de\/2025\/250222-Vorteile-der-Vergebung.mp4<\/a><\/video><\/div>\n<p><strong>Stichworte:<\/strong> einige Dinge, \u00fcber die man nachdenken sollte, um einfach und erleichtert zu leben &#8211; <a href=\"https:\/\/berliner-predigten.de\/blog\/2019\/11\/24\/der-gockel-von-kuenzelsau\/\" target=\"_blank\" rel=\"noopener\">der Gockel von K\u00fcnzelsau<\/a> &#8211; ein Leben in Frieden &#8211; was Jesus f\u00fcr uns vollbracht hat &#8211; was man loslassen kann &#8211; den D\u00e4mon der Unvers\u00f6hnlichkeit vertreiben und sich dem Heiligen Geist unterordnen<\/p>\n<p>Wer uns unterst\u00fctzen m\u00f6chte, kann dies hier tun: <a href=\"https:\/\/berliner-predigten.de\/blog\/spenden\/\" target=\"_blank\" rel=\"noopener noreferrer\">\u2665 Spenden \u2665<\/a><\/p>\n<p><strong><em>Predigt herunterladen:<\/em><\/strong><br \/>\n<em>Audio <a href=\"https:\/\/berliner-predigten.de\/dateien\/2025-02-22-Vorteile-der-Vergebung.mp3\" target=\"_blank\" rel=\"noopener noreferrer\">2025-02-22 Vorteile der Vergebung<\/a><\/em><br \/>\n<em>Video <a href=\"https:\/\/video-predigten.de\/2025\/250222-Vorteile-der-Vergebung.mp4\" target=\"_blank\" rel=\"noopener\">Vorteile der Vergebung<\/a><\/em><\/p>\n<p><a href=\"https:\/\/berliner-predigten.de\/blog\/wp-content\/uploads\/2025\/02\/250222-deine-vergangenheit.webp\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-26907 size-medium\" src=\"https:\/\/berliner-predigten.de\/blog\/wp-content\/uploads\/2025\/02\/250222-deine-vergangenheit-300x300.webp\" alt=\"Deine Vergangenheit ist ausgel\u00f6scht\" width=\"300\" height=\"300\" srcset=\"https:\/\/berliner-predigten.de\/blog\/wp-content\/uploads\/2025\/02\/250222-deine-vergangenheit-300x300.webp 300w, https:\/\/berliner-predigten.de\/blog\/wp-content\/uploads\/2025\/02\/250222-deine-vergangenheit-150x150.webp 150w, https:\/\/berliner-predigten.de\/blog\/wp-content\/uploads\/2025\/02\/250222-deine-vergangenheit-768x768.webp 768w, https:\/\/berliner-predigten.de\/blog\/wp-content\/uploads\/2025\/02\/250222-deine-vergangenheit.webp 949w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Deine Vergangenheit ist ausgel\u00f6scht, du kannst wieder bei Null anfangen. Es geht um dein Wohl. Hast du den inneren Frieden?<\/p>\n","protected":false},"author":2,"featured_media":26899,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12,2,1434],"tags":[647,164,994,2624,2623],"class_list":["post-26895","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-j-w-matutis","category-predigt","category-video","tag-unversoehnlichkeit","tag-vergebung","tag-versoehnung","tag-vorteil","tag-vorteile","comments-off"],"_links":{"self":[{"href":"https:\/\/berliner-predigten.de\/blog\/wp-json\/wp\/v2\/posts\/26895","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/berliner-predigten.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/berliner-predigten.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/berliner-predigten.de\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/berliner-predigten.de\/blog\/wp-json\/wp\/v2\/comments?post=26895"}],"version-history":[{"count":11,"href":"https:\/\/berliner-predigten.de\/blog\/wp-json\/wp\/v2\/posts\/26895\/revisions"}],"predecessor-version":[{"id":26912,"href":"https:\/\/berliner-predigten.de\/blog\/wp-json\/wp\/v2\/posts\/26895\/revisions\/26912"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/berliner-predigten.de\/blog\/wp-json\/wp\/v2\/media\/26899"}],"wp:attachment":[{"href":"https:\/\/berliner-predigten.de\/blog\/wp-json\/wp\/v2\/media?parent=26895"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/berliner-predigten.de\/blog\/wp-json\/wp\/v2\/categories?post=26895"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/berliner-predigten.de\/blog\/wp-json\/wp\/v2\/tags?post=26895"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}