{"id":26827,"date":"2025-02-15T20:24:00","date_gmt":"2025-02-15T19:24:00","guid":{"rendered":"https:\/\/berliner-predigten.de\/blog\/?p=26827"},"modified":"2025-02-16T00:26:17","modified_gmt":"2025-02-15T23:26:17","slug":"geld-ist-ein-verstaerker","status":"publish","type":"post","link":"https:\/\/berliner-predigten.de\/blog\/2025\/02\/15\/geld-ist-ein-verstaerker\/","title":{"rendered":"Geld ist ein Verst\u00e4rker"},"content":{"rendered":"<p>Sei gro\u00dfz\u00fcgig im Umgang mit anderen Menschen. Sammelt euch Sch\u00e4tze im Himmel. Geben bringt mehr Segen als Nehmen.<\/p>\n<audio class=\"wp-audio-shortcode\" id=\"audio-26827-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/berliner-predigten.de\/dateien\/2025-02-15-Geld-ist-ein-Verstaerker.mp3?_=1\" \/><a href=\"https:\/\/berliner-predigten.de\/dateien\/2025-02-15-Geld-ist-ein-Verstaerker.mp3\">https:\/\/berliner-predigten.de\/dateien\/2025-02-15-Geld-ist-ein-Verstaerker.mp3<\/a><\/audio>\n<p><!--more--><\/p>\n<div style=\"width: 640px;\" class=\"wp-video\"><video class=\"wp-video-shortcode\" id=\"video-26827-1\" width=\"640\" height=\"360\" preload=\"metadata\" controls=\"controls\"><source type=\"video\/mp4\" src=\"https:\/\/video-predigten.de\/2025\/250215-Geld-ist-ein-Verstaerker.mp4?_=1\" \/><a href=\"https:\/\/video-predigten.de\/2025\/250215-Geld-ist-ein-Verstaerker.mp4\">https:\/\/video-predigten.de\/2025\/250215-Geld-ist-ein-Verstaerker.mp4<\/a><\/video><\/div>\n<p><strong>Stichworte:<\/strong> <a href=\"https:\/\/www.schlachterbibel.de\/de\/bibel\/1_timotheus\/6\/9?hl=1#hl\" target=\"_blank\" rel=\"noopener\">einige Gedanken \u00fcber das Geld<\/a> &#8211; wie mit dem ungerechten Mammon umzugehen ist &#8211; was ich predige, habe ich selbst erlebt &#8211; wie man nutzt, was man hat<\/p>\n<p>Wer uns unterst\u00fctzen m\u00f6chte, kann dies hier tun: <a href=\"https:\/\/berliner-predigten.de\/blog\/spenden\/\" target=\"_blank\" rel=\"noopener noreferrer\">\u2665 Spenden \u2665<\/a><\/p>\n<p><strong><em>Predigt herunterladen:<\/em><\/strong><br \/>\n<em>Audio <a href=\"https:\/\/berliner-predigten.de\/dateien\/2025-02-15-Geld-ist-ein-Verstaerker.mp3\" target=\"_blank\" rel=\"noopener noreferrer\">2025-02-15 Geld ist ein Verst\u00e4rker<\/a><\/em><br \/>\n<em>Video <a href=\"https:\/\/video-predigten.de\/2025\/250215-Geld-ist-ein-Verstaerker.mp4\" target=\"_blank\" rel=\"noopener\">Geld ist ein Verst\u00e4rker<\/a><\/em><\/p>\n<p><a href=\"https:\/\/berliner-predigten.de\/blog\/wp-content\/uploads\/2025\/02\/250215-sei-grosszuegig.webp\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-26843 size-medium\" src=\"https:\/\/berliner-predigten.de\/blog\/wp-content\/uploads\/2025\/02\/250215-sei-grosszuegig-300x300.webp\" alt=\"Sei gro\u00dfz\u00fcgig im Umgang mit anderen Menschen\" width=\"300\" height=\"300\" srcset=\"https:\/\/berliner-predigten.de\/blog\/wp-content\/uploads\/2025\/02\/250215-sei-grosszuegig-300x300.webp 300w, https:\/\/berliner-predigten.de\/blog\/wp-content\/uploads\/2025\/02\/250215-sei-grosszuegig-150x150.webp 150w, https:\/\/berliner-predigten.de\/blog\/wp-content\/uploads\/2025\/02\/250215-sei-grosszuegig-768x768.webp 768w, https:\/\/berliner-predigten.de\/blog\/wp-content\/uploads\/2025\/02\/250215-sei-grosszuegig.webp 949w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sei gro\u00dfz\u00fcgig im Umgang mit anderen Menschen. Sammelt euch Sch\u00e4tze im Himmel. Geben bringt mehr Segen als Nehmen.<\/p>\n","protected":false},"author":2,"featured_media":26828,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12,2,1434],"tags":[2043,2619],"class_list":["post-26827","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-j-w-matutis","category-predigt","category-video","tag-geld","tag-verstaerker","comments-off"],"_links":{"self":[{"href":"https:\/\/berliner-predigten.de\/blog\/wp-json\/wp\/v2\/posts\/26827","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/berliner-predigten.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/berliner-predigten.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/berliner-predigten.de\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/berliner-predigten.de\/blog\/wp-json\/wp\/v2\/comments?post=26827"}],"version-history":[{"count":11,"href":"https:\/\/berliner-predigten.de\/blog\/wp-json\/wp\/v2\/posts\/26827\/revisions"}],"predecessor-version":[{"id":26846,"href":"https:\/\/berliner-predigten.de\/blog\/wp-json\/wp\/v2\/posts\/26827\/revisions\/26846"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/berliner-predigten.de\/blog\/wp-json\/wp\/v2\/media\/26828"}],"wp:attachment":[{"href":"https:\/\/berliner-predigten.de\/blog\/wp-json\/wp\/v2\/media?parent=26827"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/berliner-predigten.de\/blog\/wp-json\/wp\/v2\/categories?post=26827"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/berliner-predigten.de\/blog\/wp-json\/wp\/v2\/tags?post=26827"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}