{"id":23874,"date":"2024-04-10T18:33:01","date_gmt":"2024-04-10T16:33:01","guid":{"rendered":"https:\/\/berliner-predigten.de\/blog\/?p=23874"},"modified":"2024-04-10T23:58:09","modified_gmt":"2024-04-10T21:58:09","slug":"die-welt-geht-noch-nicht-unter","status":"publish","type":"post","link":"https:\/\/berliner-predigten.de\/blog\/2024\/04\/10\/die-welt-geht-noch-nicht-unter\/","title":{"rendered":"Die Welt geht noch nicht unter"},"content":{"rendered":"<p>Gott h\u00e4lt die ganze Welt in seiner Hand. Der Friede Gottes ist h\u00f6her als jede Vernunft. Lass dich nicht vom Teufel treiben, sondern rede mit dem lieben Gott dar\u00fcber, wo dich der Schuh dr\u00fcckt.<\/p>\n<audio class=\"wp-audio-shortcode\" id=\"audio-23874-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/berliner-predigten.de\/dateien\/2024-04-10-Die-Welt-geht-noch-nicht-unter.mp3?_=1\" \/><a href=\"https:\/\/berliner-predigten.de\/dateien\/2024-04-10-Die-Welt-geht-noch-nicht-unter.mp3\">https:\/\/berliner-predigten.de\/dateien\/2024-04-10-Die-Welt-geht-noch-nicht-unter.mp3<\/a><\/audio>\n<p><!--more--><\/p>\n<div style=\"width: 640px;\" class=\"wp-video\"><video class=\"wp-video-shortcode\" id=\"video-23874-1\" width=\"640\" height=\"360\" preload=\"metadata\" controls=\"controls\"><source type=\"video\/mp4\" src=\"https:\/\/video-predigten.de\/2024\/240410-Die-Welt-geht-noch-nicht-unter.mp4?_=1\" \/><a href=\"https:\/\/video-predigten.de\/2024\/240410-Die-Welt-geht-noch-nicht-unter.mp4\">https:\/\/video-predigten.de\/2024\/240410-Die-Welt-geht-noch-nicht-unter.mp4<\/a><\/video><\/div>\n<p><strong>Stichworte:<\/strong> Realist sein, nicht frommer Spinner &#8211; wir gehen zu Jesus &#8211; selbst Methusalah wurde nur 969 Jahre alt &#8211; praktische Tipps, um ruhig und furchtlos zu leben<\/p>\n<p>Sing mit: <a href=\"https:\/\/berliner-predigten.de\/blog\/2018\/04\/30\/himmel-und-erd-mag-brennen\/\" target=\"_blank\" rel=\"noopener\">Himmel und Erd&#8216; mag brennen<\/a> &#8211; <a href=\"https:\/\/berliner-predigten.de\/blog\/2020\/01\/27\/wer-unter-dem-schutz-des-hoechsten-wohnt\/\" target=\"_blank\" rel=\"noopener\">Wer unter dem Schutz des H\u00f6chsten wohnt<\/a><\/p>\n<p>Wer uns unterst\u00fctzen m\u00f6chte, kann dies hier tun: <a href=\"https:\/\/berliner-predigten.de\/blog\/spenden\/\" target=\"_blank\" rel=\"noopener noreferrer\">\u2665 Spenden \u2665<\/a><\/p>\n<p><strong><em>Predigt herunterladen:<\/em><\/strong><br \/>\n<em>Audio <a href=\"https:\/\/berliner-predigten.de\/dateien\/2024-04-10-Die-Welt-geht-noch-nicht-unter.mp3\" target=\"_blank\" rel=\"noopener noreferrer\">2024-04-10 Die Welt geht noch nicht unter<\/a><\/em><br \/>\n<em>Video <a href=\"https:\/\/video-predigten.de\/2024\/240410-Die-Welt-geht-noch-nicht-unter.mp4\" target=\"_blank\" rel=\"noopener\">Die Welt geht noch nicht unter<\/a><\/em><\/p>\n<p><a href=\"https:\/\/berliner-predigten.de\/blog\/wp-content\/uploads\/2024\/04\/240410-gott-haelt-die-ganze-welt.webp\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-23880 size-medium\" src=\"https:\/\/berliner-predigten.de\/blog\/wp-content\/uploads\/2024\/04\/240410-gott-haelt-die-ganze-welt-300x300.webp\" alt=\"Gott h\u00e4lt die ganze Welt in seiner Hand\" width=\"300\" height=\"300\" srcset=\"https:\/\/berliner-predigten.de\/blog\/wp-content\/uploads\/2024\/04\/240410-gott-haelt-die-ganze-welt-300x300.webp 300w, https:\/\/berliner-predigten.de\/blog\/wp-content\/uploads\/2024\/04\/240410-gott-haelt-die-ganze-welt-150x150.webp 150w, https:\/\/berliner-predigten.de\/blog\/wp-content\/uploads\/2024\/04\/240410-gott-haelt-die-ganze-welt-768x768.webp 768w, https:\/\/berliner-predigten.de\/blog\/wp-content\/uploads\/2024\/04\/240410-gott-haelt-die-ganze-welt.webp 949w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gott h\u00e4lt die ganze Welt in seiner Hand. Der Friede Gottes ist h\u00f6her als jede Vernunft. Lass dich nicht vom Teufel treiben, sondern rede mit dem lieben Gott dar\u00fcber, wo dich der Schuh dr\u00fcckt.<\/p>\n","protected":false},"author":2,"featured_media":23876,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12,2,1434],"tags":[613,32,1006,227,1323,1013,754,1839],"class_list":["post-23874","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-j-w-matutis","category-predigt","category-video","tag-angst","tag-ermutigung","tag-furchtlos","tag-gebet","tag-noch-nicht","tag-untergehen","tag-welt","tag-weltuntergangsstimmung","comments-off"],"_links":{"self":[{"href":"https:\/\/berliner-predigten.de\/blog\/wp-json\/wp\/v2\/posts\/23874","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/berliner-predigten.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/berliner-predigten.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/berliner-predigten.de\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/berliner-predigten.de\/blog\/wp-json\/wp\/v2\/comments?post=23874"}],"version-history":[{"count":10,"href":"https:\/\/berliner-predigten.de\/blog\/wp-json\/wp\/v2\/posts\/23874\/revisions"}],"predecessor-version":[{"id":23887,"href":"https:\/\/berliner-predigten.de\/blog\/wp-json\/wp\/v2\/posts\/23874\/revisions\/23887"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/berliner-predigten.de\/blog\/wp-json\/wp\/v2\/media\/23876"}],"wp:attachment":[{"href":"https:\/\/berliner-predigten.de\/blog\/wp-json\/wp\/v2\/media?parent=23874"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/berliner-predigten.de\/blog\/wp-json\/wp\/v2\/categories?post=23874"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/berliner-predigten.de\/blog\/wp-json\/wp\/v2\/tags?post=23874"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}