{"id":22356,"date":"2023-11-17T16:39:54","date_gmt":"2023-11-17T15:39:54","guid":{"rendered":"https:\/\/berliner-predigten.de\/blog\/?p=22356"},"modified":"2023-11-17T22:26:38","modified_gmt":"2023-11-17T21:26:38","slug":"weltweite-endzeit-warnungen-2","status":"publish","type":"post","link":"https:\/\/berliner-predigten.de\/blog\/2023\/11\/17\/weltweite-endzeit-warnungen-2\/","title":{"rendered":"Weltweite Endzeit-Warnungen"},"content":{"rendered":"<p>Es werden wieder massenweise Dumme gesucht. Das Ende steht vor der T\u00fcr wie kurz vor Noahs Flut. F\u00fcrchte dich nicht!<\/p>\n<audio class=\"wp-audio-shortcode\" id=\"audio-22356-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/berliner-predigten.de\/dateien\/2023-11-17-Weltweite-Endzeit-Warnungen.mp3?_=1\" \/><a href=\"https:\/\/berliner-predigten.de\/dateien\/2023-11-17-Weltweite-Endzeit-Warnungen.mp3\">https:\/\/berliner-predigten.de\/dateien\/2023-11-17-Weltweite-Endzeit-Warnungen.mp3<\/a><\/audio>\n<p><!--more--><\/p>\n<div style=\"width: 640px;\" class=\"wp-video\"><video class=\"wp-video-shortcode\" id=\"video-22356-1\" width=\"640\" height=\"360\" preload=\"metadata\" controls=\"controls\"><source type=\"video\/mp4\" src=\"https:\/\/video-predigten.de\/2023\/231117-Weltweite-Endzeit-Warnungen.mp4?_=1\" \/><a href=\"https:\/\/video-predigten.de\/2023\/231117-Weltweite-Endzeit-Warnungen.mp4\">https:\/\/video-predigten.de\/2023\/231117-Weltweite-Endzeit-Warnungen.mp4<\/a><\/video><\/div>\n<p><strong>Stichworte:<\/strong> Teilen und Herrschen &#8211; fromme Vampire &#8211; einige Zeichen der Endzeit &#8211; Lauheit, Tr\u00e4gheit und erkaltete Liebe &#8211; <a href=\"https:\/\/www.schlachterbibel.de\/de\/bibel\/offenbarung\/11\/1\/#hl\" target=\"_blank\" rel=\"noopener\">der Krieg gegen die Heiligen und die zwei Zeugen<\/a> &#8211; wenn das Geld wichtiger ist &#8211; Gott macht Unterschiede &#8211; Gottes Gericht und des Teufels Selbstmord<\/p>\n<p>Sing mit: <a href=\"https:\/\/berliner-predigten.de\/blog\/2018\/05\/01\/wenn-auch-steile-und-ragende-berge\/\" target=\"_blank\" rel=\"noopener\">Wenn auch steile und ragende Berge<\/a> &#8211; <a href=\"https:\/\/berliner-predigten.de\/blog\/2020\/01\/27\/wer-unter-dem-schutz-des-hoechsten-wohnt\/\" target=\"_blank\" rel=\"noopener\">Wer unter dem Schutz des H\u00f6chsten wohnt<\/a><\/p>\n<p>Wer uns unterst\u00fctzen m\u00f6chte, kann dies hier tun: <a href=\"https:\/\/berliner-predigten.de\/blog\/spenden\/\" target=\"_blank\" rel=\"noopener noreferrer\">\u2665 Spenden \u2665<\/a><\/p>\n<p><strong><em>Predigt herunterladen:<\/em><\/strong><br \/>\n<em>Audio <a href=\"https:\/\/berliner-predigten.de\/dateien\/2023-11-17-Weltweite-Endzeit-Warnungen.mp3\" target=\"_blank\" rel=\"noopener noreferrer\">2023-11-17 Weltweite Endzeit-Warnungen<\/a><\/em><br \/>\n<em>Video <a href=\"https:\/\/video-predigten.de\/2023\/231117-Weltweite-Endzeit-Warnungen.mp4\" target=\"_blank\" rel=\"noopener\">Weltweite Endzeit-Warnungen<\/a><\/em><\/p>\n<p><a href=\"https:\/\/berliner-predigten.de\/blog\/wp-content\/uploads\/2023\/11\/231117-es-werden-wieder-dumme-gesucht.webp\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-22377 size-medium\" src=\"https:\/\/berliner-predigten.de\/blog\/wp-content\/uploads\/2023\/11\/231117-es-werden-wieder-dumme-gesucht-300x300.webp\" alt=\"Es werden wieder massenweise Dumme gesucht\" width=\"300\" height=\"300\" srcset=\"https:\/\/berliner-predigten.de\/blog\/wp-content\/uploads\/2023\/11\/231117-es-werden-wieder-dumme-gesucht-300x300.webp 300w, https:\/\/berliner-predigten.de\/blog\/wp-content\/uploads\/2023\/11\/231117-es-werden-wieder-dumme-gesucht-150x150.webp 150w, https:\/\/berliner-predigten.de\/blog\/wp-content\/uploads\/2023\/11\/231117-es-werden-wieder-dumme-gesucht-768x768.webp 768w, https:\/\/berliner-predigten.de\/blog\/wp-content\/uploads\/2023\/11\/231117-es-werden-wieder-dumme-gesucht.webp 949w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Es werden wieder massenweise Dumme gesucht. Das Ende steht vor der T\u00fcr wie kurz vor Noahs Flut. F\u00fcrchte dich nicht!<\/p>\n","protected":false},"author":2,"featured_media":22362,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12,2,1434],"tags":[2280,2281,945],"class_list":["post-22356","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-j-w-matutis","category-predigt","category-video","tag-endzeit-warnung","tag-teilen-und-herrschen","tag-weltweit","comments-off"],"_links":{"self":[{"href":"https:\/\/berliner-predigten.de\/blog\/wp-json\/wp\/v2\/posts\/22356","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/berliner-predigten.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/berliner-predigten.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/berliner-predigten.de\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/berliner-predigten.de\/blog\/wp-json\/wp\/v2\/comments?post=22356"}],"version-history":[{"count":20,"href":"https:\/\/berliner-predigten.de\/blog\/wp-json\/wp\/v2\/posts\/22356\/revisions"}],"predecessor-version":[{"id":22381,"href":"https:\/\/berliner-predigten.de\/blog\/wp-json\/wp\/v2\/posts\/22356\/revisions\/22381"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/berliner-predigten.de\/blog\/wp-json\/wp\/v2\/media\/22362"}],"wp:attachment":[{"href":"https:\/\/berliner-predigten.de\/blog\/wp-json\/wp\/v2\/media?parent=22356"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/berliner-predigten.de\/blog\/wp-json\/wp\/v2\/categories?post=22356"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/berliner-predigten.de\/blog\/wp-json\/wp\/v2\/tags?post=22356"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}