{"id":19297,"date":"2023-01-01T22:13:14","date_gmt":"2023-01-01T21:13:14","guid":{"rendered":"https:\/\/berliner-predigten.de\/blog\/?p=19297"},"modified":"2023-01-08T11:32:07","modified_gmt":"2023-01-08T10:32:07","slug":"themen-der-woche-2023-01","status":"publish","type":"post","link":"https:\/\/berliner-predigten.de\/blog\/2023\/01\/01\/themen-der-woche-2023-01\/","title":{"rendered":"Themen der Woche 2023\/01"},"content":{"rendered":"<p>Die Themen f\u00fcr die Woche 2023\/01 im <a href=\"https:\/\/gemeindezentrum.berlin\/\" target=\"_blank\" rel=\"noopener noreferrer\">Gemeinde-Zentrum<\/a> \u2013 komm vorbei oder h\u00f6re <a href=\"https:\/\/www.facebook.com\/johannes.matutis\" target=\"_blank\" rel=\"noopener\">Pastor Joh. W. Matutis<\/a> im Internet (jeweils 2 Stunden sp\u00e4ter).<\/p>\n<p>Mittwoch, 4. Januar 2023, 16 Uhr:<br \/>\n<a href=\"https:\/\/berliner-predigten.de\/blog\/2023\/01\/04\/eine-neue-zeit-beginnt\/\"><strong>Eine neue Zeit beginnt<\/strong><\/a><\/p>\n<p>Freitag, 6. Januar 2023, 19 Uhr:<br \/>\n<a href=\"https:\/\/berliner-predigten.de\/blog\/2023\/01\/06\/lass-deine-traeume-wahr-werden\/\"><strong>Lass deine Tr\u00e4ume wahr werden<\/strong><\/a><\/p>\n<p>Samstag, 7. Januar 2023, 19 Uhr:<br \/>\n<a href=\"https:\/\/berliner-predigten.de\/blog\/2023\/01\/07\/lebe-ein-glueckliches-leben-3\/\"><strong>Lebe ein gl\u00fcckliches Leben<\/strong><\/a><\/p>\n<p>Sonntag, 8. Januar 2023, 10 Uhr:<br \/>\n<a href=\"https:\/\/berliner-predigten.de\/blog\/2023\/01\/08\/lebe-aus-der-fuelle\/\"><strong>Lebe aus der F\u00fclle<\/strong><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Themen f\u00fcr die Woche 2023\/01 im Gemeinde-Zentrum \u2013 komm vorbei oder h\u00f6re Pastor Joh. W. Matutis im Internet (jeweils 2 Stunden sp\u00e4ter). Mittwoch, 4. Januar 2023, 16 Uhr: Eine neue Zeit beginnt Freitag, 6. Januar 2023, 19 Uhr: Lass deine Tr\u00e4ume wahr werden Samstag, 7. Januar 2023, 19 Uhr: Lebe ein gl\u00fcckliches Leben Sonntag, 8. Januar 2023, 10 Uhr: Lebe aus der F\u00fclle<\/p>\n","protected":false},"author":2,"featured_media":19321,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-19297","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-termine-und-themen","comments-off"],"_links":{"self":[{"href":"https:\/\/berliner-predigten.de\/blog\/wp-json\/wp\/v2\/posts\/19297","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/berliner-predigten.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/berliner-predigten.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/berliner-predigten.de\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/berliner-predigten.de\/blog\/wp-json\/wp\/v2\/comments?post=19297"}],"version-history":[{"count":6,"href":"https:\/\/berliner-predigten.de\/blog\/wp-json\/wp\/v2\/posts\/19297\/revisions"}],"predecessor-version":[{"id":19432,"href":"https:\/\/berliner-predigten.de\/blog\/wp-json\/wp\/v2\/posts\/19297\/revisions\/19432"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/berliner-predigten.de\/blog\/wp-json\/wp\/v2\/media\/19321"}],"wp:attachment":[{"href":"https:\/\/berliner-predigten.de\/blog\/wp-json\/wp\/v2\/media?parent=19297"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/berliner-predigten.de\/blog\/wp-json\/wp\/v2\/categories?post=19297"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/berliner-predigten.de\/blog\/wp-json\/wp\/v2\/tags?post=19297"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}