{"id":18631,"date":"2022-11-20T11:27:47","date_gmt":"2022-11-20T10:27:47","guid":{"rendered":"https:\/\/berliner-predigten.de\/blog\/?p=18631"},"modified":"2022-11-20T13:50:12","modified_gmt":"2022-11-20T12:50:12","slug":"gibt-es-ein-leben-nach-dem-tod","status":"publish","type":"post","link":"https:\/\/berliner-predigten.de\/blog\/2022\/11\/20\/gibt-es-ein-leben-nach-dem-tod\/","title":{"rendered":"Gibt es ein Leben nach dem Tod?"},"content":{"rendered":"<p>Woher kommen wir, wohin gehen wir? Unsere ewige Seele braucht immer einen K\u00f6rper. Selig sind, die nicht sehen und doch glauben.<\/p>\n<audio class=\"wp-audio-shortcode\" id=\"audio-18631-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/berliner-predigten.de\/dateien\/2022-11-20-Gibt-es-ein-Leben-nach-dem-Tod.mp3?_=1\" \/><a href=\"https:\/\/berliner-predigten.de\/dateien\/2022-11-20-Gibt-es-ein-Leben-nach-dem-Tod.mp3\">https:\/\/berliner-predigten.de\/dateien\/2022-11-20-Gibt-es-ein-Leben-nach-dem-Tod.mp3<\/a><\/audio>\n<p><!--more--><\/p>\n<div style=\"width: 640px;\" class=\"wp-video\"><video class=\"wp-video-shortcode\" id=\"video-18631-1\" width=\"640\" height=\"360\" preload=\"metadata\" controls=\"controls\"><source type=\"video\/mp4\" src=\"https:\/\/video-predigten.de\/2022\/221120-Gibt-es-ein-Leben-nach-dem-Tod.mp4?_=1\" \/><a href=\"https:\/\/video-predigten.de\/2022\/221120-Gibt-es-ein-Leben-nach-dem-Tod.mp4\">https:\/\/video-predigten.de\/2022\/221120-Gibt-es-ein-Leben-nach-dem-Tod.mp4<\/a><\/video><\/div>\n<p><strong>Stichworte:<\/strong> faszinierende und r\u00e4tselhafte Nahtoderfahrungen &#8211; verschiedenste und ungewisse Vorstellungen \u00fcber das Jenseits &#8211; unser Leben geht weiter &#8211; wo sind unsere Lieben? &#8211; K\u00f6rper und Gehirn &#8211; Seele, Geist und neuer Leib &#8211; wor\u00fcber Jesus nach der Auferstehung gesprochen hat &#8211; <a href=\"https:\/\/www.schlachterbibel.de\/de\/bibel\/jona\/4\/5-11?hl=1#hl\" target=\"_blank\" rel=\"noopener\">Jonas Jammern wegen einem Rizinusstrauch<\/a> &#8211; <a href=\"https:\/\/www.schlachterbibel.de\/de\/bibel\/johannes\/11\/25?hl=1#hl\" target=\"_blank\" rel=\"noopener\">wer an mich glaubt, wird leben, auch wenn er stirbt<\/a> &#8211; <a href=\"https:\/\/www.schlachterbibel.de\/de\/bibel\/hesekiel\/37\/1-14?hl=1#hl\" target=\"_blank\" rel=\"noopener\">Menschensohn, k\u00f6nnen diese Gebeine wieder lebendig werden?<\/a> &#8211; <a href=\"https:\/\/www.schlachterbibel.de\/de\/bibel\/2_korinther\/5\/1-5?hl=1#hl\" target=\"_blank\" rel=\"noopener\">der \u00e4u\u00dfere und der unsichtbare Mensch<\/a> &#8211; Jesus ist Herr \u00fcber Tote und Lebendige<\/p>\n<p>Wer uns unterst\u00fctzen m\u00f6chte, kann dies hier tun: <a href=\"https:\/\/berliner-predigten.de\/blog\/spenden\/\" target=\"_blank\" rel=\"noopener noreferrer\">\u2665 Spenden \u2665<\/a><\/p>\n<p><strong><em>Predigt herunterladen:<\/em><\/strong><br \/>\n<em>Audio <a href=\"https:\/\/berliner-predigten.de\/dateien\/2022-11-20-Gibt-es-ein-Leben-nach-dem-Tod.mp3\" target=\"_blank\" rel=\"noopener noreferrer\">2022-11-20 Gibt es ein Leben nach dem Tod?<\/a><\/em><br \/>\n<em>Video <a href=\"https:\/\/video-predigten.de\/2022\/221120-Gibt-es-ein-Leben-nach-dem-Tod.mp4\" target=\"_blank\" rel=\"noopener\">Gibt es ein Leben nach dem Tod?<\/a><\/em><\/p>\n<p><a href=\"https:\/\/berliner-predigten.de\/blog\/wp-content\/uploads\/2022\/11\/221120-woher-kommen-wir.webp\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-18649 size-medium\" src=\"https:\/\/berliner-predigten.de\/blog\/wp-content\/uploads\/2022\/11\/221120-woher-kommen-wir-300x300.webp\" alt=\"Woher kommen wir, wohin gehen wir\" width=\"300\" height=\"300\" srcset=\"https:\/\/berliner-predigten.de\/blog\/wp-content\/uploads\/2022\/11\/221120-woher-kommen-wir-300x300.webp 300w, https:\/\/berliner-predigten.de\/blog\/wp-content\/uploads\/2022\/11\/221120-woher-kommen-wir-150x150.webp 150w, https:\/\/berliner-predigten.de\/blog\/wp-content\/uploads\/2022\/11\/221120-woher-kommen-wir-768x768.webp 768w, https:\/\/berliner-predigten.de\/blog\/wp-content\/uploads\/2022\/11\/221120-woher-kommen-wir.webp 949w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Woher kommen wir, wohin gehen wir? Unsere ewige Seele braucht immer einen K\u00f6rper. Selig sind, die nicht sehen und doch glauben.<\/p>\n","protected":false},"author":2,"featured_media":18633,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12,2,1434],"tags":[711,46,1927,1959,222,119,156],"class_list":["post-18631","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-j-w-matutis","category-predigt","category-video","tag-auferstehung","tag-es-gibt","tag-jenseits","tag-leben-nach-dem-tod","tag-nach-dem-tod","tag-seele","tag-sterben","comments-off"],"_links":{"self":[{"href":"https:\/\/berliner-predigten.de\/blog\/wp-json\/wp\/v2\/posts\/18631","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/berliner-predigten.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/berliner-predigten.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/berliner-predigten.de\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/berliner-predigten.de\/blog\/wp-json\/wp\/v2\/comments?post=18631"}],"version-history":[{"count":20,"href":"https:\/\/berliner-predigten.de\/blog\/wp-json\/wp\/v2\/posts\/18631\/revisions"}],"predecessor-version":[{"id":18654,"href":"https:\/\/berliner-predigten.de\/blog\/wp-json\/wp\/v2\/posts\/18631\/revisions\/18654"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/berliner-predigten.de\/blog\/wp-json\/wp\/v2\/media\/18633"}],"wp:attachment":[{"href":"https:\/\/berliner-predigten.de\/blog\/wp-json\/wp\/v2\/media?parent=18631"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/berliner-predigten.de\/blog\/wp-json\/wp\/v2\/categories?post=18631"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/berliner-predigten.de\/blog\/wp-json\/wp\/v2\/tags?post=18631"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}