{"id":16398,"date":"2022-06-26T13:23:30","date_gmt":"2022-06-26T11:23:30","guid":{"rendered":"https:\/\/berliner-predigten.de\/blog\/?p=16398"},"modified":"2022-07-03T11:59:39","modified_gmt":"2022-07-03T09:59:39","slug":"themen-der-woche-2022-26","status":"publish","type":"post","link":"https:\/\/berliner-predigten.de\/blog\/2022\/06\/26\/themen-der-woche-2022-26\/","title":{"rendered":"Themen der Woche 2022\/26"},"content":{"rendered":"<p>Die Themen f\u00fcr die Woche 2022\/26 im <a href=\"https:\/\/gemeindezentrum.berlin\/\" target=\"_blank\" rel=\"noopener noreferrer\">Gemeinde-Zentrum<\/a> \u2013 komm vorbei oder h\u00f6re <a href=\"https:\/\/www.facebook.com\/johannes.matutis\" target=\"_blank\" rel=\"noopener\">Pastor Joh. W. Matutis<\/a> im Internet (jeweils 2 Stunden sp\u00e4ter).<\/p>\n<p>Mittwoch, 29. Juni 2022, 16 Uhr:<br \/>\n<a href=\"https:\/\/berliner-predigten.de\/blog\/2022\/06\/29\/jesus-wartet-auf-dich\/\"><strong>Jesus wartet auf dich<\/strong><\/a><\/p>\n<p>Freitag, 1. Juli 2022, 19 Uhr:<br \/>\n<a href=\"https:\/\/berliner-predigten.de\/blog\/2022\/07\/01\/werde-fertig-mit-deinen-giganten\/\"><strong>Werde fertig mit deinen Giganten<\/strong><\/a><\/p>\n<p>Samstag, 2. Juli 2022, 19 Uhr:<br \/>\n<a href=\"https:\/\/berliner-predigten.de\/blog\/2022\/07\/02\/werde-der-herr-deines-lebens\/\"><strong>Werde der Herr deines Lebens<\/strong><\/a><\/p>\n<p>Sonntag, 3. Juli 2022, 10 Uhr:<br \/>\n<a href=\"https:\/\/berliner-predigten.de\/blog\/2022\/07\/03\/vertraue-deinen-soldaten\/\"><strong>Vertraue deinen Soldaten<\/strong><\/a><\/p>\n<hr \/>\n<p>Keine Predigt verpassen? Unser E-Mail-Rundbrief wird viermal pro Woche verschickt und informiert \u00fcber aktuelle Termine und Themen. \u2709\ufe0f <a href=\"https:\/\/berliner-predigten.de\/blog\/newsletter\/\" target=\"_blank\" rel=\"noopener\">E-Mail-Rundbrief abonnieren!<\/a> \u2709\ufe0f<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Themen f\u00fcr die Woche 2022\/26 im Gemeinde-Zentrum \u2013 komm vorbei oder h\u00f6re Pastor Joh. W. Matutis im Internet (jeweils 2 Stunden sp\u00e4ter). Mittwoch, 29. Juni 2022, 16 Uhr: Jesus wartet auf dich Freitag, 1. Juli 2022, 19 Uhr: Werde fertig mit deinen Giganten Samstag, 2. Juli 2022, 19 Uhr: Werde der Herr deines Lebens Sonntag, 3. Juli 2022, 10 Uhr: Vertraue deinen Soldaten Keine Predigt verpassen? Unser E-Mail-Rundbrief wird viermal pro Woche verschickt und informiert \u00fcber aktuelle Termine und Themen. \u2709\ufe0f E-Mail-Rundbrief abonnieren! \u2709\ufe0f<\/p>\n","protected":false},"author":2,"featured_media":16399,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-16398","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-termine-und-themen","comments-off"],"_links":{"self":[{"href":"https:\/\/berliner-predigten.de\/blog\/wp-json\/wp\/v2\/posts\/16398","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/berliner-predigten.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/berliner-predigten.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/berliner-predigten.de\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/berliner-predigten.de\/blog\/wp-json\/wp\/v2\/comments?post=16398"}],"version-history":[{"count":7,"href":"https:\/\/berliner-predigten.de\/blog\/wp-json\/wp\/v2\/posts\/16398\/revisions"}],"predecessor-version":[{"id":16522,"href":"https:\/\/berliner-predigten.de\/blog\/wp-json\/wp\/v2\/posts\/16398\/revisions\/16522"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/berliner-predigten.de\/blog\/wp-json\/wp\/v2\/media\/16399"}],"wp:attachment":[{"href":"https:\/\/berliner-predigten.de\/blog\/wp-json\/wp\/v2\/media?parent=16398"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/berliner-predigten.de\/blog\/wp-json\/wp\/v2\/categories?post=16398"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/berliner-predigten.de\/blog\/wp-json\/wp\/v2\/tags?post=16398"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}